{"id":7499,"date":"2023-09-16T23:50:10","date_gmt":"2023-09-16T21:50:10","guid":{"rendered":"https:\/\/alaincardenas.com\/blog\/?p=7499"},"modified":"2023-09-18T20:15:49","modified_gmt":"2023-09-18T18:15:49","slug":"sylvie-vervaert-quand-la-permanence-des-images-mene-aux-collections-parcours-dune-marchande-dart-erudite","status":"publish","type":"post","link":"https:\/\/alaincardenas.com\/blog\/sylvie-vervaert-quand-la-permanence-des-images-mene-aux-collections-parcours-dune-marchande-dart-erudite\/","title":{"rendered":"Sylvie Vervaet, quand la permanence des images m\u00e8ne aux collections. Parcours d\u2019une marchande d\u2019art \/ \u00e9rudite"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">par Alain Cardenas-Castro et Christophe Comentale<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Art et n\u00e9goce, les alternances des images, celles que l\u2019on cr\u00e9e, celles que l\u2019on voit, que l\u2019on revoit et que l\u2019on identifie, entre imaginaire et histoire de la culture. Portrait d\u2019une cr\u00e9atrice et marchande d\u2019art d\u00e9couvreuse de talents et de pi\u00e8ces patrimoniales, de Picasso \u00e0 Zhang Hua.<\/p>\n\n\n\n<div class=\"wp-block-jetpack-slideshow aligncenter\" data-effect=\"slide\"><div class=\"wp-block-jetpack-slideshow_container swiper-container\"><ul class=\"wp-block-jetpack-slideshow_swiper-wrapper swiper-wrapper\"><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"270\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-7515\" data-id=\"7515\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/1694869079941.jpg?resize=584%2C270&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/1694869079941.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/1694869079941.jpg?resize=300%2C139&amp;ssl=1 300w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/1694869079941.jpg?resize=768%2C356&amp;ssl=1 768w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/1694869079941.jpg?resize=500%2C231&amp;ssl=1 500w\" sizes=\"(max-width: 584px) 100vw, 584px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"438\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-7511\" data-id=\"7511\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/1-SV-Gd-Palais-ephemere-sept21-1.jpg?resize=584%2C438&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/1-SV-Gd-Palais-ephemere-sept21-1.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/1-SV-Gd-Palais-ephemere-sept21-1.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/1-SV-Gd-Palais-ephemere-sept21-1.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/1-SV-Gd-Palais-ephemere-sept21-1.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/1-SV-Gd-Palais-ephemere-sept21-1.jpg?w=1080&amp;ssl=1 1080w\" sizes=\"(max-width: 584px) 100vw, 584px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"509\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-7510\" data-id=\"7510\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/0-SV-face-St-Joseoh-1.jpg?resize=584%2C509&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/0-SV-face-St-Joseoh-1.jpg?w=688&amp;ssl=1 688w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/0-SV-face-St-Joseoh-1.jpg?resize=300%2C262&amp;ssl=1 300w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/0-SV-face-St-Joseoh-1.jpg?resize=344%2C300&amp;ssl=1 344w\" sizes=\"(max-width: 584px) 100vw, 584px\" \/><\/figure><\/li><\/ul><a class=\"wp-block-jetpack-slideshow_button-prev swiper-button-prev swiper-button-white\" role=\"button\"><\/a><a class=\"wp-block-jetpack-slideshow_button-next swiper-button-next swiper-button-white\" role=\"button\"><\/a><a aria-label=\"Pause Slideshow\" class=\"wp-block-jetpack-slideshow_button-pause\" role=\"button\"><\/a><div class=\"wp-block-jetpack-slideshow_pagination swiper-pagination swiper-pagination-white\"><\/div><\/div><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"has-text-align-center has-small-font-size wp-block-paragraph\">\u00a0Ci-dessus.\u00a0<em>Sylvie Vervaet<\/em>, photographies r\u00e9centes (Sylvie Vervaet dans son loft-galerie ; le stand au Salon international du livre rare et des arts graphiques du Grand Palais \u00e9ph\u00e9m\u00e8re, session 2022 ; Sylvie Vervaet pr\u00e9sentant un panneau du 16e si\u00e8cle,\u00a0<em>Saint Joseph et l&rsquo;enfant J\u00e9sus<\/em>).<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Les ann\u00e9es 1970 sont celles d\u2019un apprentissage et d\u2019une formation tr\u00e8s compl\u00e9mentaires avec la fr\u00e9quentation des ateliers de gravure de Lagrange et Dorny aux Beaux-arts de Paris, puis un cursus \u00e0 Paris 1 sur le site Saint Charles et et \u00e0 l\u2019Ecole nationale sup\u00e9rieure des arts d\u00e9coratifs dans les ateliers peinture de Zao Wou-ki et gravure de Fiorini et Heudes. Sylvie Vervaet s\u2019int\u00e9resse \u00e0 la cr\u00e9ation autant qu\u2019\u00e0 la th\u00e9orie des arts. Sa cr\u00e9ation se double d\u2019un plaisir de la d\u00e9couverte, celle des \u0153uvres, des images, celle des gens aussi. Sans oublier le plaisir qu\u2019elle a \u00e0 d\u00e9couvrir des lieux, travers\u00e9s au fil de ses nombreux voyages en diff\u00e9rents pays d\u2019Europe mais aussi en Am\u00e9rique du Sud et du Nord. (Argentine, Br\u00e9sil, Mexique, New York) Afrique du nord, (Tunisie, Maroc) et Gr\u00e8ce, Turquie, \u2026 Elle encha\u00eene aussi les m\u00e9tiers, travaille un temps comme iconographe pour une encyclop\u00e9die, devient enseignante en arts plastiques et quittant rapidement ce m\u00e9tier, s\u2019initie \u00e0 la vente d\u2019\u0153uvres d\u2019art, principalement des \u0153uvres graphiques et picturales, de sculptures aussi, devenant marchande d\u2019art. Elle ach\u00e8te alors de la peinture des dessins et des gravures, des \u0153uvres de tous si\u00e8cles mais ce sont surtout les grands mouvements de l\u2019histoire de l\u2019art qui la passionnent, les surr\u00e9alistes, les abstraits, les singuliers et bien d\u2019autres\u2026. Son \u0153il de peintre alli\u00e9 \u00e0 sa connaissance de l\u2019histoire de l\u2019art et des techniques diverses acquises par sa pratique lui permettent d\u2019acqu\u00e9rir avec assurance les \u0153uvres qui viennent, comme naturellement \u00e0 elles, crois\u00e9es sur son chemin\u2026<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/2-Kees-van-DongenLe-serpent-de-la-Genese-etui-a-pinceau-1901-1.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"648\" data-attachment-id=\"7516\" data-permalink=\"https:\/\/alaincardenas.com\/blog\/sylvie-vervaert-quand-la-permanence-des-images-mene-aux-collections-parcours-dune-marchande-dart-erudite\/2-kees-van-dongenle-serpent-de-la-genese-etui-a-pinceau-1901-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/2-Kees-van-DongenLe-serpent-de-la-Genese-etui-a-pinceau-1901-1.jpg?fit=692%2C768&amp;ssl=1\" data-orig-size=\"692,768\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 14 Pro Max&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1694165340&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;2.22&quot;,&quot;iso&quot;:&quot;500&quot;,&quot;shutter_speed&quot;:&quot;0.02&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"2-Kees-van-DongenLe-serpent-de-la-Genese-etui-a-pinceau-1901-1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/2-Kees-van-DongenLe-serpent-de-la-Genese-etui-a-pinceau-1901-1.jpg?fit=584%2C648&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/2-Kees-van-DongenLe-serpent-de-la-Genese-etui-a-pinceau-1901-1.jpg?resize=584%2C648&#038;ssl=1\" alt=\"\" class=\"wp-image-7516\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/2-Kees-van-DongenLe-serpent-de-la-Genese-etui-a-pinceau-1901-1.jpg?w=692&amp;ssl=1 692w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/2-Kees-van-DongenLe-serpent-de-la-Genese-etui-a-pinceau-1901-1.jpg?resize=270%2C300&amp;ssl=1 270w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a><figcaption class=\"wp-element-caption\"><strong>Kees van Dongen<\/strong>, <em>Serpent<\/em> (1901), \u00e9tui \u00e0 pinceaux, L. 34,5 cm, diam. 5 cm<\/figcaption><\/figure>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/3-Kees-van-Dongen-Jeune-fille-torse-nu-1901.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"451\" height=\"768\" data-attachment-id=\"7504\" data-permalink=\"https:\/\/alaincardenas.com\/blog\/sylvie-vervaert-quand-la-permanence-des-images-mene-aux-collections-parcours-dune-marchande-dart-erudite\/3-kees-van-dongen-jeune-fille-torse-nu-1901\/\" data-orig-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/3-Kees-van-Dongen-Jeune-fille-torse-nu-1901.jpg?fit=451%2C768&amp;ssl=1\" data-orig-size=\"451,768\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 14 Pro Max&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1694165312&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;2.22&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.02&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"3 &amp;#8211; Kees van Dongen, Jeune fille torse nu, 1901\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/3-Kees-van-Dongen-Jeune-fille-torse-nu-1901.jpg?fit=451%2C768&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/3-Kees-van-Dongen-Jeune-fille-torse-nu-1901.jpg?resize=451%2C768&#038;ssl=1\" alt=\"\" class=\"wp-image-7504\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/3-Kees-van-Dongen-Jeune-fille-torse-nu-1901.jpg?w=451&amp;ssl=1 451w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/3-Kees-van-Dongen-Jeune-fille-torse-nu-1901.jpg?resize=176%2C300&amp;ssl=1 176w\" sizes=\"auto, (max-width: 451px) 100vw, 451px\" \/><\/a><figcaption class=\"wp-element-caption\"><strong>Kees van Dongen<\/strong>, <em>Jeune fille torse nu<\/em> (1901), dessin double face, 14 x 8 cm<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong>Paris, 1980, les ab\u00eemes du n\u00e9goce<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette proximit\u00e9 aux \u0153uvres, elle ne s\u2019est pas troubl\u00e9e, elle n\u2019a pas cess\u00e9, elle ne s\u2019est pas d\u00e9mentie.&nbsp;\u00ab Il y a cette adr\u00e9naline de la d\u00e9couverte, une d\u00e9couverte que le regard permet de cerner, de conforter, ou, au contraire, d\u2019\u00e9liminer de fa\u00e7on r\u00e9dhibitoire&nbsp;\u00bb confie la marchande d\u2019art tout en compulsant ses fiches et archives diverses.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u00ab J\u2019avais, continue-t-elle, toujours trouv\u00e9 que le regard d\u2019un cr\u00e9ateur, en l\u2019occurrence mon regard de peintre, \u00e9tait beaucoup plus pertinent et efficace face \u00e0 une \u0153uvre connue, peu identifi\u00e9e ou compl\u00e8tement ignor\u00e9e. J\u2019ai beaucoup \u00e9tudi\u00e9 les techniques de r\u00e9alisation des \u0153uvres, tant les mat\u00e9riaux qui permettent de r\u00e9aliser des uniques, acrylique, huile, techniques mixtes, ou bien les \u0153uvres multiples. Ces multiples, il faut un \u0153il qui distingue avec facilit\u00e9, avec naturel, s\u2019il s\u2019agit d\u2019une taille directe, pointe s\u00e8che ou burin, en creux ou en relief ou encore si la s\u00e9rigraphie ou la lithographie sont rehauss\u00e9es. De ce constat technique d\u00e9rive tr\u00e8s naturellement un diagnostic d\u2019identification, de rang presque, dans ce processus qui am\u00e8ne \u00e0 d\u00e9terminer le nom du cr\u00e9ateur qui est derri\u00e8re tout cela \u00bb.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Par ailleurs, et avant m\u00eame de conclure sur un nom, il faut aussi rappeler l\u2019importance des rencontres humaines comme le rappelle cette anecdote. \u00a0\u00bb&nbsp;Je trouvai un jour sur un march\u00e9 d\u2019art un tableau sign\u00e9 Beloff. La force de l\u2019\u0153uvre m\u2019avait comme magn\u00e9tis\u00e9e. Il me fallut alors trouver de qui il s\u2019agissait, ce que je fis \u00ab\u00a0. Il s\u2019agissait d\u2019une femme-peintre, Angelina Beloff (1879, Saint Petersbourg &#8211; 1969, Mexico), la femme de l\u2019artiste mexicain, muraliste, Diego Rivera (1886, Guanajuato &#8211; 1957, San Angel). Angelina Beloff [\u0410\u043d\u0433\u0435\u043b\u0438\u043d\u0430 \u041f\u0435\u0442\u0440\u043e\u0432\u043d\u0430 \u0411\u0435\u043b\u043e\u0432\u0430] \u00e9tait une peintre de paysage, elle n\u2019appartenant nullement au courant cubiste, contrairement \u00e0 son \u00e9poux, qui \u0153uvre \u00e0 des \u0153uvres vraiment cubistes de 1910 \u00e0 1920. Or, ce jour, Sylvie Vervaet est face \u00e0 des \u0153uvres des deux \u00e9poux. Enthousiaste, elle prend en charge le commissariat d\u2019expositions qui sont un axe autre et tout \u00e0 fait compl\u00e9mentaire pour diffuser des connaissances, en l\u2019occurrence, une approche du travail des artistes.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/4-Gauguin-Le-sourire-1.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"370\" data-attachment-id=\"7517\" data-permalink=\"https:\/\/alaincardenas.com\/blog\/sylvie-vervaert-quand-la-permanence-des-images-mene-aux-collections-parcours-dune-marchande-dart-erudite\/4-gauguin-le-sourire-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/4-Gauguin-Le-sourire-1.jpg?fit=1080%2C685&amp;ssl=1\" data-orig-size=\"1080,685\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"4-Gauguin-Le-sourire-1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/4-Gauguin-Le-sourire-1.jpg?fit=584%2C370&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/4-Gauguin-Le-sourire-1.jpg?resize=584%2C370&#038;ssl=1\" alt=\"\" class=\"wp-image-7517\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/4-Gauguin-Le-sourire-1.jpg?resize=1024%2C649&amp;ssl=1 1024w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/4-Gauguin-Le-sourire-1.jpg?resize=300%2C190&amp;ssl=1 300w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/4-Gauguin-Le-sourire-1.jpg?resize=768%2C487&amp;ssl=1 768w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/4-Gauguin-Le-sourire-1.jpg?resize=473%2C300&amp;ssl=1 473w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/4-Gauguin-Le-sourire-1.jpg?w=1080&amp;ssl=1 1080w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a><figcaption class=\"wp-element-caption\"><strong>Paul Gauguin<\/strong>, <em>Le sourire<\/em> (1899)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Le travail d\u2019une passeuse d\u2019art<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsqu\u2019on p\u00e9n\u00e8tre dans l\u2019immense atelier-scriptorium o\u00f9 Sylvie Vervaet conserve une imposante documentation et des \u0153uvres tr\u00e8s diversifi\u00e9es, on est accueilli par un splendide portait de Saint Joseph et de l\u2019enfant J\u00e9sus. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">il s\u2019agirait \u2014 explique notre guide \u2014 d\u2019un autoportrait de L\u00e9onard de Vinci, comme le repr\u00e9senta Rapha\u00ebl, par admiration pour le ma\u00eetre. Cette \u0153uvre du 16<sup>e<\/sup> si\u00e8cle, est comme fr\u00e9quemment \u00e0 l\u2019\u00e9poque, d\u00e9pourvu de signature. Le lien fort qui unit l\u2019homme au jeune enfant est plein d\u2019une tendresse toute paternelle.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Exemple embl\u00e9matique de l\u2019approche large et \u00e9rudite qui permet au fil des ann\u00e9es \u00e0 cette marchande d\u2019art \u00e9rudite de ne pas mener une carri\u00e8re qui va privil\u00e9gier surtout les \u0153uvres modernes et contemporaines. &nbsp;Ainsi, depuis les ann\u00e9es 90, outre une pr\u00e9sence aux grands salons internationaux tourn\u00e9s vers l\u2019art actuel, elle multiplie une pr\u00e9sence professionnelle en prenant un stand au march\u00e9 de Saint-Ouen, continue avec brio \u00e0 dresser son stand sur celui de Vanves deux matin\u00e9es chaque week-end, un lieu o\u00f9 les amateurs et collectionneurs se succ\u00e8dent pour en savoir plus sur les \u0153uvres en parall\u00e8le \u00e0 du conseil en mati\u00e8re d\u2019art, pour les \u0153uvres patrimoniales, certaines toiles ou panneaux datant des 16<sup>e<\/sup>, 17<sup>e<\/sup> s., mais ce sont surtout les 20<sup>e<\/sup> et 21<sup>e<\/sup> si\u00e8cles qui ont sa faveur, \u00ab&nbsp;en raison de la diversit\u00e9 ouverte de ses mouvements artistiques&nbsp;\u00bb dit-elle. Un cr\u00e9neau qui rassemble surtout des pi\u00e8ces \u00e0 son go\u00fbt&nbsp;: l\u2019art brut, les \u0153uvres de Gaston Chaissac ou de Jean Dubuffet, l\u2019art singulier avec les \u0153uvres d\u2019Yvon Taillandier, Michel Macr\u00e9au (1935-1995). De m\u00eame, le courant surr\u00e9aliste et ses \u00e9manations, de Chirico, puis Err\u00f3, Michaux. Sans oublier l\u2019Ecole de Paris, dont la classification large et la distinction entre la premi\u00e8re et la deuxi\u00e8me \u00e9cole ont produit une majorit\u00e9 d\u2019\u0153uvres figuratives. Telles sont les directions suivies et pour lesquelles une documentation importante compl\u00e8te les diagnostics in situ. <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/5-Arthur-Aesbacher-Zingueur-de-paupieres-1962.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"541\" height=\"768\" data-attachment-id=\"7506\" data-permalink=\"https:\/\/alaincardenas.com\/blog\/sylvie-vervaert-quand-la-permanence-des-images-mene-aux-collections-parcours-dune-marchande-dart-erudite\/5-arthur-aesbacher-zingueur-de-paupieres-1962\/\" data-orig-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/5-Arthur-Aesbacher-Zingueur-de-paupieres-1962.jpg?fit=541%2C768&amp;ssl=1\" data-orig-size=\"541,768\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.78&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 14 Pro Max&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1694115335&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.86&quot;,&quot;iso&quot;:&quot;1000&quot;,&quot;shutter_speed&quot;:&quot;0.016666666666667&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"5 &amp;#8211; Arthur Aesbacher, Zingueur de paupie\u0300res, 1962\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/5-Arthur-Aesbacher-Zingueur-de-paupieres-1962.jpg?fit=541%2C768&amp;ssl=1\" data-id=\"7506\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/5-Arthur-Aesbacher-Zingueur-de-paupieres-1962.jpg?resize=541%2C768&#038;ssl=1\" alt=\"\" class=\"wp-image-7506\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/5-Arthur-Aesbacher-Zingueur-de-paupieres-1962.jpg?w=541&amp;ssl=1 541w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/5-Arthur-Aesbacher-Zingueur-de-paupieres-1962.jpg?resize=211%2C300&amp;ssl=1 211w\" sizes=\"auto, (max-width: 541px) 100vw, 541px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/6-Monique-Rozanes-sans-titre-2020.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"779\" data-attachment-id=\"7507\" data-permalink=\"https:\/\/alaincardenas.com\/blog\/sylvie-vervaert-quand-la-permanence-des-images-mene-aux-collections-parcours-dune-marchande-dart-erudite\/6-monique-rozanes-sans-titre-2020\/\" data-orig-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/6-Monique-Rozanes-sans-titre-2020.jpg?fit=810%2C1080&amp;ssl=1\" data-orig-size=\"810,1080\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"6 &amp;#8211; Monique Rozanes, sans titre, 2020\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/6-Monique-Rozanes-sans-titre-2020.jpg?fit=584%2C779&amp;ssl=1\" data-id=\"7507\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/6-Monique-Rozanes-sans-titre-2020.jpg?resize=584%2C779&#038;ssl=1\" alt=\"\" class=\"wp-image-7507\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/6-Monique-Rozanes-sans-titre-2020.jpg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/6-Monique-Rozanes-sans-titre-2020.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/6-Monique-Rozanes-sans-titre-2020.jpg?w=810&amp;ssl=1 810w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"has-text-align-left has-small-font-size wp-block-paragraph\">Ci-dessus, de gauche \u00e0 droite. <strong>Arthur Aesbacher<\/strong> [1923-2020], <em>Patte court v\u00eatue<\/em> (1961), collage, 26 x 19 cm ; <strong>Monique Rozanes<\/strong> [1936, Bordeaux], <em>Sans titre<\/em> (2020), plexiglas, H. 27 cm, diam. 21,5 cm<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Lorsque j\u2019accueille mes visiteurs, des clients de longue date pour certains, \u00e0 mon stand, j\u2019ai toujours le m\u00eame plaisir, celui des \u00e9changes, du dialogue. Ce n\u2019est qu\u2019une partie visible de ce qui constitue cet iceberg dont une importante face cach\u00e9e est la recherche d\u2019\u0153uvres, les visites d\u2019ateliers o\u00f9 des fonds s\u2019empoussi\u00e8rent, de maisons de particuliers voulant vendre des \u0153uvres jug\u00e9es hors de leurs pr\u00e9occupations, tout comme autant les livraisons d\u2019\u0153uvres importantes aux collectionneurs dans le doute s\u2019accompagnent de conseils divers. <em>Cette approche \u00e0 des cr\u00e9ateurs du monde entier permet \u00e0 la marchande d\u2019art \u00e9galement cr\u00e9atrice que je suis, de garder cette envie, ce d\u00e9sir de voir de nouvelles images, des images toutes travers\u00e9es par des talents multiples et aussi de les faire partager \u00e0 mes collectionneurs, devenus, pour certains, des amis d\u00e9sireux d\u2019\u00e9changes et de surprises inattendues face aux \u0153uvres. Et enfin, il reste un d\u00e9sir tr\u00e8s fort, celui de la d\u00e9couverte toujours renouvel\u00e9e et des \u00e9motions esth\u00e9tiques face \u00e0 des \u0153uvres que j&rsquo;appelle mes p\u00e9pites\u2026 Je suis en quelque sorte une chercheuse d\u2019art ! Zhang Hua&nbsp;(ca 1898-1970)&nbsp;en est une illustration importante&nbsp;; je poss\u00e8de un fonds de quelque 600 pi\u00e8ces de cet artiste dont j\u2019ai pu faire appr\u00e9cier le talent \u00e0 diff\u00e9rents collectionneurs. Je r\u00e9fl\u00e9chis actuellement \u00e0 un projet d\u2019exposition en France et surtout en Chine, m\u00e8re patrie de cet exil\u00e9 au trait impulsif et soutenu<\/em>,<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">compl\u00e8te Sylvie Vervaet. Les d\u00e9couvertes ne cessent de se multiplier au fil du temps et de sa r\u00e9putation qui suscite des contacts, des visites, souvent suivi de moissons inattendues&nbsp;: une toile du 16e si\u00e8cle, un Tiepolo ou un Morandi aux tons oscillant entre des ocres et des tons c\u00e9ladons surprenants et superbes, des gravures par de Kooning et cet \u00e9tonnant artiste chinois, Zhang Hua,&nbsp;\u00e0 la polychromie intense et parcourues d\u2019une gestuelle calligraphiques. Ce sont l\u00e0&nbsp; autant de moyens de montrer cette diversit\u00e9 active de l&rsquo;art moderne et contemporain et les correspondances secr\u00e8tes qui sous-tend la vie de toutes ces oeuvres et le plaisir magique que cette d\u00e9couvreuse d&rsquo;images poss\u00e8de \u00e0 les r\u00e9v\u00e9ler.&nbsp;<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/7-Zhang-Hua-Abstraction-hst.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"507\" height=\"1024\" data-attachment-id=\"7508\" data-permalink=\"https:\/\/alaincardenas.com\/blog\/sylvie-vervaert-quand-la-permanence-des-images-mene-aux-collections-parcours-dune-marchande-dart-erudite\/7-zhang-hua-abstraction-hst\/\" data-orig-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/7-Zhang-Hua-Abstraction-hst.jpg?fit=507%2C1024&amp;ssl=1\" data-orig-size=\"507,1024\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1461976366&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.28&quot;,&quot;iso&quot;:&quot;500&quot;,&quot;shutter_speed&quot;:&quot;0.066666666666667&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"7 &amp;#8211; Zhang Hua, Abstraction, hst\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/7-Zhang-Hua-Abstraction-hst.jpg?fit=507%2C1024&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/7-Zhang-Hua-Abstraction-hst.jpg?resize=507%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-7508\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/7-Zhang-Hua-Abstraction-hst.jpg?w=507&amp;ssl=1 507w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/09\/7-Zhang-Hua-Abstraction-hst.jpg?resize=149%2C300&amp;ssl=1 149w\" sizes=\"auto, (max-width: 507px) 100vw, 507px\" \/><\/a><figcaption class=\"wp-element-caption\"><strong>Zhang Hua<\/strong>, <em>Sans titre<\/em> (ca 1955), huile sur toile<\/figcaption><\/figure>\n<\/div>\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Cet artiste \u2014 explique Sylvie Vervaet \u2014, je l\u2019ai connu par hasard, alors que j\u2019avais rendez-vous chez un encadreur d\u00e9j\u00e0 occup\u00e9 \u00e0 faire des projets de cadre pour un client poss\u00e9dant un fonds limit\u00e9 d\u2019\u0153uvres sur papier de Zhang Hua. Le dialogue s\u2019est \u00e9tabli, j\u2019ai pu avoir acc\u00e8s \u00e0 un fonds dont je poss\u00e8de quelque 600 pi\u00e8ces. J\u2019ai pu faire appr\u00e9cier ce talentueux peintre \u00e0 diff\u00e9rents collectionneurs, je r\u00e9fl\u00e9chis actuellement \u00e0 un projet d\u2019exposition en France et surtout en Chine, m\u00e8re patrie de cet exil\u00e9 au trait impulsif et soutenu. Cette approche \u00e0 des cr\u00e9ateurs du monde entier permet \u00e0 la marchande d\u2019art \u00e9galement cr\u00e9atrice que je suis, de garder cette envie, ce d\u00e9sir de voir de nouvelles images, des images toutes travers\u00e9es par des talents multiples et aussi de les faire partager \u00e0 mes collectionneurs, devenus, pour certains, des amis d\u00e9sireux d\u2019\u00e9changes et de surprises inattendues face aux \u0153uvres. Et enfin, il reste un d\u00e9sir tr\u00e8s fort, celui de la d\u00e9couverte et des \u00e9motions esth\u00e9tiques face \u00e0 une \u0153uvre.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Rep\u00e8res bibliographiques<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Site de Sylvie Vervaet&nbsp;: <a href=\"https:\/\/www.artvie-galerie.com\/\">www.artvie-galerie.com<\/a><\/li>\n\n\n\n<li>Sylvie Vervaet, <em>Van Dongen, Neuf dessins et un \u00e9tui \u00e0 pinceaux<\/em>. Paris&nbsp;: Artvie-galerie, 2022. 13 p.&nbsp;: ill. en coul.<\/li>\n\n\n\n<li>Christophe Comentale, <em>Cent ans d\u2019art en Chine, 1920-2020<\/em>. Paris&nbsp;: Ed. du Cano\u00eb, 2023. 544 p.&nbsp;: 607 ill. Bibliog. Index.<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">\u897f\u5c14\u7ef4\u00b7\u97e6\u5c14\u74e6\u7279\uff08SYLVIE VERVAET\uff09\uff0c\u5f53\u56fe\u50cf\u7684\u6301\u4e45\u6027\u5bfc\u81f4\u6536\u85cf\u65f6\u3002<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u827a\u672f\u54c1\u7ecf\u9500\u5546\u7684\u65c5\u7a0b\u3002<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u827a\u672f\u4e0e\u8d38\u6613\uff0c\u56fe\u50cf\u7684\u4ea4\u66ff\uff0c\u6211\u4eec\u521b\u9020\u7684\uff0c\u6211\u4eec\u770b\u5230\u7684\uff0c\u56de\u987e\u548c\u8bc6\u522b\u7684\uff0c\u5728\u60f3\u8c61\u548c\u6587\u5316\u5386\u53f2\u4e4b\u95f4\u3002\u4e00\u4f4d\u53d1\u73b0\u4ece\u6bd5\u52a0\u7d22\u5230\u5f20\u534e\u7684\u624d\u534e\u548c\u9057\u4ea7\u4f5c\u54c1\u7684\u521b\u4f5c\u8005\u548c\u827a\u672f\u54c1\u7ecf\u9500\u5546\u7684\u8096\u50cf\u3002<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u572870\u5e74\u4ee3\u7684\u5927\u5b66\u5b66\u4e60\u4e4b\u540e\uff0c\u5df4\u9ece\u7f8e\u672f\u5b66\u9662\u5728\u83f2\u5965\u91cc\u5c3c\u548c\u591a\u5c3c\u7684\u5e73\u9762\u827a\u672f\u5de5\u4f5c\u5ba4\uff0c\u5df4\u9ece\u7b2c\u4e00\u5723\u67e5\u5c14\u65af\u548c\u56fd\u7acb\u9ad8\u7b49\u88c5\u9970\u827a\u672f\u5b66\u9662\uff0cSylvie Vervaet\u5bf9\u521b\u4f5c\u548c\u827a\u672f\u7406\u8bba\u4e00\u6837\u611f\u5174\u8da3\u3002\u4ed6\u7684\u521b\u4f5c\u4f34\u968f\u7740\u53d1\u73b0\u7684\u4e50\u8da3\uff0c\u4f5c\u54c1\uff0c\u56fe\u50cf\uff0c\u4eba\u3002.\u4ed6\u7684\u521b\u4f5c\u4f34\u968f\u7740\u53d1\u73b0\u7684\u4e50\u8da3\uff0c\u4f5c\u54c1\uff0c\u56fe\u50cf\uff0c\u4eba\u3002\u66f4\u4e0d\u7528\u8bf4\u5979\u53d1\u73b0\u5730\u65b9\u7684\u4e50\u8da3\uff0c\u7a7f\u8d8a\u4e86\u4e0d\u540c\u56fd\u5bb6\u7684\u65c5\u884c\uff0c\u5df4\u897f\uff0c\u5317\u7f8e\u3002\u5979\u8fd8\u5728\u9152\u5427\u5de5\u4f5c\u4e86\u4e00\u6bb5\u65f6\u95f4\uff0c\u6210\u4e3a\u4e00\u540d\u89c6\u89c9\u827a\u672f\u8001\u5e08\uff0c\u5e76\u5bf9\u4f5c\u54c1\u7684\u9500\u552e\u4ea7\u751f\u4e86\u5174\u8da3\uff0c\u6210\u4e3a\u53e4\u8463\u5546\u548c\u4e8c\u624b\u5546\u3002\u7136\u540e\u5979\u8d2d\u4e70\u7ed8\u753b\uff0c\u5404\u4e2a\u4e16\u7eaa\u7684\u4f5c\u54c1\uff0c\u4f46\u8ba9\u5979\u7740\u8ff7\u7684\u662f\u62bd\u8c61\u4f5c\u54c1\uff0c\u5979\u7684\u753b\u5bb6\u7684\u773c\u775b\u8ba9\u5979\u83b7\u5f97\u4e86\u4e00\u79cd\u611f\u89c9\uff0c\u8fd9\u4e5f\u662f\u521b\u4f5c\u8005\u70ed\u7231\u96d5\u523b\u3001\u7ed8\u753b\u6216\u5199\u4f5c\u7684\u611f\u89c9\u3002<\/p>\n","protected":false},"excerpt":{"rendered":"<p>par Alain Cardenas-Castro et Christophe Comentale Art et n\u00e9goce, les alternances des images, celles que l\u2019on cr\u00e9e, celles que l\u2019on voit, que l\u2019on revoit et que l\u2019on identifie, entre imaginaire et histoire de la culture. Portrait d\u2019une cr\u00e9atrice et marchande &hellip; <a href=\"https:\/\/alaincardenas.com\/blog\/sylvie-vervaert-quand-la-permanence-des-images-mene-aux-collections-parcours-dune-marchande-dart-erudite\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[41,42,1,22],"tags":[32,8,33,36],"class_list":["post-7499","post","type-post","status-publish","format-standard","hentry","category-asie","category-europe","category-oeuvre","category-portrait","tag-art-chinois","tag-art-contemporain","tag-collection","tag-foires-et-salons"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8Mijt-1WX","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":9650,"url":"https:\/\/alaincardenas.com\/blog\/lart-brut-est-ouest-nouvelles-approches-nouvelles-images\/","url_meta":{"origin":7499,"position":0},"title":"L\u2019ART BRUT, EST-OUEST, NOUVELLES APPROCHES, NOUVELLES IMAGES.","author":"admin","date":"2026-05-27","format":false,"excerpt":"Art brut \u00e0 Montpellier - Lausanne \u2013 Paris \u2013 Taipei - Cuzco par Alain Cardenas-Castro et Christophe Comentale [abstract en anglais, espagnol, chinois. Texte en fran\u00e7ais] La figure embl\u00e9matique de Jean Dubuffet et ses choix esth\u00e9tiques restent, certes, un jalon significatif et fondamental de ce qui est devenu \u2014 appellation\u2026","rel":"","context":"Dans &quot;Am\u00e9rique latine&quot;","block_context":{"text":"Am\u00e9rique latine","link":"https:\/\/alaincardenas.com\/blog\/category\/amerique-latine\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2026\/05\/Horace-Diaz-animaux.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5385,"url":"https:\/\/alaincardenas.com\/blog\/une-symphonie-de-couleurs-lexposition-yang-ermin-au-musee-dart-et-dhistoire-louis-senlecq-de-lisle-adam\/","url_meta":{"origin":7499,"position":1},"title":"Une symphonie de couleurs\u00a0:  l\u2019exposition Yang Ermin au mus\u00e9e d\u2019Art et d\u2019Histoire Louis-Senlecq  de L\u2019Isle-Adam","author":"admin","date":"2020-10-12","format":false,"excerpt":"par Marie Laureillard Le mus\u00e9e d\u2019Art et d\u2019Histoire Louis-Senlecq de L\u2019Isle-Adam propose une exposition intitul\u00e9e Yang Ermin\u00a0: la r\u00e9apparition de la couleur\u00a0du 19 septembre 2020 au 14 f\u00e9vrier 2021, accompagn\u00e9e d\u2019un catalogue publi\u00e9 aux \u00e9ditions Faton (\u00ab\u00a0coup de c\u0153ur\u00a0\u00bb de la Librairie le Ph\u00e9nix). Pr\u00e9sent\u00e9 pour la quatri\u00e8me fois en\u2026","rel":"","context":"Dans &quot;Asie&quot;","block_context":{"text":"Asie","link":"https:\/\/alaincardenas.com\/blog\/category\/asie\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/10\/YEM-AFFICHE-40x60_OK3-BD.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/10\/YEM-AFFICHE-40x60_OK3-BD.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/10\/YEM-AFFICHE-40x60_OK3-BD.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":4363,"url":"https:\/\/alaincardenas.com\/blog\/a-la-croisee-de-collections-dart-entre-asie-et-occident-du-xixe-siecle-a-nos-jours\/","url_meta":{"origin":7499,"position":2},"title":"A la crois\u00e9e de collections d\u2019art entre Asie et Occident (du XIXe si\u00e8cle \u00e0 nos jours)","author":"admin","date":"2019-11-24","format":false,"excerpt":"Ouvrage collectif dirig\u00e9 par Marie Laureillard et Cl\u00e9a Patin, \u00e9ditions H\u00e9misph\u00e8res, 2019\u00a0(417 pages de texte + 72 pages d\u2019illustrations couleur). par\u00a0Marie Laureillard Depuis trois si\u00e8cles au moins, l\u2019Occident est fascin\u00e9 par l\u2019art d\u2019Extr\u00eame-Orient. Les Asiatiques, quant \u00e0 eux, collectionnent leur propre production artistique \u00e0 diverses fins ou se passionnent pour\u2026","rel":"","context":"Dans &quot;Asie&quot;","block_context":{"text":"Asie","link":"https:\/\/alaincardenas.com\/blog\/category\/asie\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2019\/11\/image001-196x300.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":9536,"url":"https:\/\/alaincardenas.com\/blog\/juan-diego-vergaga-dix-ans-de-silence-et-de-foule-chez-picasso\/","url_meta":{"origin":7499,"position":3},"title":"JUAN DIEGO VERGARA\u00a0: DIX ANS DE SILENCE ET DE FOULE CHEZ PICASSO.","author":"admin","date":"2026-07-08","format":false,"excerpt":"Exposition d\u2019\u0153uvres panoramiques et intimes Espace d\u2019exposition Couronnes. Galerie des AAB, 1 rue Francis Picabia, Paris 20e, du mardi 3 sept.au lundi 13 sept. 2026. Vernissage le 3 sept. d\u00e8s 18h30. [L\u2019anniversaire de l\u2019artiste tombe le 7 septembre]\u00a0; l\u2019espace est ouvert du jeudi au dimanche, de 14h \u00e0 19h Juan\u2026","rel":"","context":"Dans &quot;Am\u00e9rique latine&quot;","block_context":{"text":"Am\u00e9rique latine","link":"https:\/\/alaincardenas.com\/blog\/category\/amerique-latine\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2026\/07\/Juan-Diego-volante.pdf_20260307_093635_0000.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2026\/07\/Juan-Diego-volante.pdf_20260307_093635_0000.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2026\/07\/Juan-Diego-volante.pdf_20260307_093635_0000.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2026\/07\/Juan-Diego-volante.pdf_20260307_093635_0000.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":8890,"url":"https:\/\/alaincardenas.com\/blog\/karen-arbulu-de-la-sobriete-sacree-des-parures-davant-garde\/","url_meta":{"origin":7499,"position":4},"title":"KAREN ARBUL\u00da : DE LA SOBRIETE SACREE DES PARURES D\u2019AVANT-GARDE","author":"admin","date":"2025-05-21","format":false,"excerpt":"par Alain-Cardenas Castro et Christophe Comentale Karen Arbul\u00fa (1957, Lima) a re\u00e7u en don une habilet\u00e9 non seulement manuelle, mais aussi celui, plus mouvant de l\u2019art de conter une histoire impossible\u00a0: elle sait tirer parti d\u2019une histoire et d\u2019une culture qui se rejoignent \u00e0 travers des pi\u00e8ces d\u2019une orf\u00e8vrerie unique,\u2026","rel":"","context":"Dans &quot;Am\u00e9rique latine&quot;","block_context":{"text":"Am\u00e9rique latine","link":"https:\/\/alaincardenas.com\/blog\/category\/amerique-latine\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2025\/05\/1744220705442.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2025\/05\/1744220705442.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2025\/05\/1744220705442.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":1786,"url":"https:\/\/alaincardenas.com\/blog\/notes-de-qiu-le-projet-des-lanternes-multicolores\/","url_meta":{"origin":7499,"position":5},"title":"Notes de Qiu : le Projet des Lanternes Multicolores","author":"admin","date":"2018-04-24","format":false,"excerpt":"\u90b1\u6ce8\u4e0a\u5143\u706f\u5f69\u8ba1\u5212 P\u00e9kin, Mus\u00e9e d\u2019Art Contemporain Minsheng\u00a0du 16 Mars 2018 au 5 Mai 2018 Compte-rendu d'exposition\u00a0par Fanny Paldacci Vendredi 16 Mars a eu lieu le vernissage de l\u2019exposition Notes de Qiu : le Projet des Lanternes Multicolores au mus\u00e9e d\u2019art contemporain Minsheng, \u00e0 Beijing (P\u00e9kin). Ce long projet a \u00e9t\u00e9 initi\u00e9\u2026","rel":"","context":"Dans &quot;Asie&quot;","block_context":{"text":"Asie","link":"https:\/\/alaincardenas.com\/blog\/category\/asie\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2018\/04\/27.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2018\/04\/27.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2018\/04\/27.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2018\/04\/27.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/posts\/7499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/comments?post=7499"}],"version-history":[{"count":17,"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/posts\/7499\/revisions"}],"predecessor-version":[{"id":7539,"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/posts\/7499\/revisions\/7539"}],"wp:attachment":[{"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/media?parent=7499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/categories?post=7499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/tags?post=7499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}