{"id":7096,"date":"2023-05-21T11:11:05","date_gmt":"2023-05-21T09:11:05","guid":{"rendered":"https:\/\/alaincardenas.com\/blog\/?p=7096"},"modified":"2023-07-11T21:35:29","modified_gmt":"2023-07-11T19:35:29","slug":"concours-du-livre-dartiste-dissy-les-moulineaux-stephanie-ferrat-laureate-2023","status":"publish","type":"post","link":"https:\/\/alaincardenas.com\/blog\/concours-du-livre-dartiste-dissy-les-moulineaux-stephanie-ferrat-laureate-2023\/","title":{"rendered":"Concours du livre d\u2019artiste d\u2019Issy-les-Moulineaux, St\u00e9phanie Ferrat laur\u00e9ate 2023."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Compte-rendu.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">par Marie-Paule Peronnet (*)<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Depuis six ans, cette manifestation met l\u2019accent sur la pluralit\u00e9 du type de cr\u00e9ation \u00e0 la fois r\u00e9cent et historique que constitue le livre d\u2019artiste. Apparu en Occident vers le 19<sup>e<\/sup> si\u00e8cle selon certains, en Chine sous la dynastie des Song (10<sup>e<\/sup>-12<sup>e<\/sup> si\u00e8cles) pour d\u2019autres, il a d\u00e9j\u00e0 fait l\u2019objet de nombreuses recherches et attentions qui ont abouti \u00e0 la constitution de collections tr\u00e8s diverses. A ce jour, 1000 titres \u00e9toffent le fonds de la m\u00e9diath\u00e8que d\u2019Issy.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">A Marion Nino, Directrice des M\u00e9diath\u00e8ques d\u2019Issy-les-Moulineaux, le mot du d\u00e9but : \u00ab <strong>Ce sont les mains qui font, qui vont en silence, et le livre est n\u00e9 <\/strong>\u00bb. Ces mots de St\u00e9phanie Ferrat, laur\u00e9ate du prix du livre d\u2019Artiste de la Ville d\u2019Issy-les-Moulineaux, nous rappellent l\u2019ampleur de l\u2019univers dans lequel se d\u00e9ploie un livre d\u2019artiste : \u0153uvre compl\u00e8te, \u00e0 la fois plastique, organique et po\u00e9tique, il trouve une place naturelle dans l\u2019esp\u00e9rance un peu folle des biblioth\u00e8ques de rassembler dans leurs murs savoirs et artistes. Cette ann\u00e9e encore, la M\u00e9diath\u00e8que centre-ville se r\u00e9jouit de contribuer modestement par ce concours \u00e0 valoriser l\u2019extr\u00eame diversit\u00e9 et richesse des cr\u00e9ateurs de livres d\u2019artistes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un r\u00e8glement publi\u00e9 tr\u00e8s en amont permet notamment aux cr\u00e9ateurs int\u00e9ress\u00e9s de pr\u00e9parer un livre r\u00e9cent et in\u00e9dit, pour la circonstance. Les laur\u00e9ats des ann\u00e9es pr\u00e9c\u00e9dentes ne peuvent \u00e0 nouveau candidater.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comme chaque ann\u00e9e, un jury tr\u00e8s \u00e0 l\u2019\u00e9coute de la diversit\u00e9 de ce que peut \u00eatre un livre d\u2019artiste, s\u2019est rassembl\u00e9 afin de d\u00e9cerner le prix au laur\u00e9at. Sa composition est donn\u00e9e ci-apr\u00e8s&nbsp;:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Candice Attard, directrice des affaires culturelles \u00e0 la mairie d&rsquo;Issy-les-Moulineaux, Gwenael Beuchet, charg\u00e9 de conservation au <a href=\"https:\/\/www.museecarteajouer.com\/\">Mus\u00e9e de la carte \u00e0 jouer d&rsquo;Issy-les-Moulineaux<\/a>, Alain Cardenas-Castro, enseignant, artiste et m\u00e9diateur scientifique et culturel au Mus\u00e9um national d&rsquo;Histoire naturelle, Christophe Comentale, auteur, conservateur en chef honoraire au Museum national d&rsquo;Histoire naturelle, Laetitia Cuisinier, charg\u00e9e de programmation culturelle, Fr\u00e9d\u00e9ric Harranger (**), Virgile Legrand, galeriste et \u00e9diteur, Marie Minssieux-Chamonard, conservatrice en chef \u00e0 la&nbsp;Biblioth\u00e8que nationale de France,&nbsp;responsable des collections XXe-XXIe si\u00e8cles, r\u00e9serve des livres rares, Marion Nino, conservatrice en chef, directrice des <a href=\"https:\/\/mediatheques.ville-issy.fr\/\">m\u00e9diath\u00e8ques de la ville d&rsquo;Issy-les-Moulineaux<\/a>, Jean-Marc Thommen, artiste et directeur de l&rsquo;\u00e9cole d&rsquo;art <a href=\"https:\/\/www.issy.com\/lesarcades\">\u00ab\u00a0Les Arcades\u00a0\u00bb<\/a>, H\u00e9l\u00e8ne Valotteau, conservatrice en chef, responsable du p\u00f4le jeunesse et patrimoine \u00e0 l&rsquo;Heure Joyeuse, M\u00e9diath\u00e8que Fran\u00e7oise Sagan.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">&#8211;<strong>1 <\/strong><em>Un d\u00e9mon gentil mod\u00e8le<\/em>. Marie-Christine Dauphin. D\u2019apr\u00e8s un texte de Christian Bobin. \u0152uvre compos\u00e9e de trois \u00e9l\u00e9ments&nbsp;: leporello de 10 x 16 cm, d\u00e9coupage et collages&nbsp;; livret 16 x 10 cm qui r\u00e9organise les expressions enti\u00e8res&nbsp;; un recueil d\u2019aphorismes, 4 x 9 cm. Exemplaire unique.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/02\/1-un-demon-gentil-modele-Marie-Christine-Dauphin-2.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"438\" data-attachment-id=\"7250\" data-permalink=\"https:\/\/alaincardenas.com\/blog\/la-serie-des-fonds-or-a-propos-dun-recent-paysage-de-fan-yifu\/1-un-demon-gentil-modele-marie-christine-dauphin-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/02\/1-un-demon-gentil-modele-Marie-Christine-Dauphin-2.jpg?fit=1024%2C768&amp;ssl=1\" data-orig-size=\"1024,768\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 8&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1683826815&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.99&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"1, un de\u0301mon gentil mode\u0300le, Marie-Christine Dauphin-2\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/02\/1-un-demon-gentil-modele-Marie-Christine-Dauphin-2.jpg?fit=584%2C438&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/02\/1-un-demon-gentil-modele-Marie-Christine-Dauphin-2.jpg?resize=584%2C438&#038;ssl=1\" alt=\"\" class=\"wp-image-7250\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/02\/1-un-demon-gentil-modele-Marie-Christine-Dauphin-2.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/02\/1-un-demon-gentil-modele-Marie-Christine-Dauphin-2.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/02\/1-un-demon-gentil-modele-Marie-Christine-Dauphin-2.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/02\/1-un-demon-gentil-modele-Marie-Christine-Dauphin-2.jpg?resize=400%2C300&amp;ssl=1 400w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211;<strong>2 <\/strong><em>Lignes de cr\u00eates. <\/em>Catherine Decellas, texte de Fran\u00e7ois Cheng. Leporello sculpt\u00e9 aux formes des motifs. Aquarelle. Texte manuscrit.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dipl\u00f4m\u00e9e d\u2019art textile et arts appliqu\u00e9s, Catherine Decellas \u00e9labore des livres d\u2019artiste depuis 1993. Ce sont plus pr\u00e9cis\u00e9ment des leporelli (livres en accord\u00e9on) peints tels des panoramiques. Dans ces \u0153uvres, peinture, encre et po\u00e9sie se r\u00e9pondent. Les couvertures sont \u00e9galement travaill\u00e9es dans l\u2019esprit de chaque livre. L\u2018artiste s\u2019inspire entre autres de textes de po\u00e8tes tels que Fran\u00e7ois Cheng, Andr\u00e9e Chedid&#8230;Chaque exemplaire est unique.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/2-lignes-de-cretes-Catherine-Decellas.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"326\" data-attachment-id=\"7125\" data-permalink=\"https:\/\/alaincardenas.com\/blog\/concours-du-livre-dartiste-dissy-les-moulineaux-stephanie-ferrat-laureate-2023\/2-lignes-de-cretes-catherine-decellas\/\" data-orig-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/2-lignes-de-cretes-Catherine-Decellas.jpg?fit=1024%2C572&amp;ssl=1\" data-orig-size=\"1024,572\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 8&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1683826964&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.99&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.04&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"2, lignes de cre\u0302tes, Catherine Decellas\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/2-lignes-de-cretes-Catherine-Decellas.jpg?fit=584%2C326&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/2-lignes-de-cretes-Catherine-Decellas.jpg?resize=584%2C326&#038;ssl=1\" alt=\"\" class=\"wp-image-7125\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/2-lignes-de-cretes-Catherine-Decellas.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/2-lignes-de-cretes-Catherine-Decellas.jpg?resize=300%2C168&amp;ssl=1 300w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/2-lignes-de-cretes-Catherine-Decellas.jpg?resize=768%2C429&amp;ssl=1 768w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/2-lignes-de-cretes-Catherine-Decellas.jpg?resize=500%2C279&amp;ssl=1 500w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211;<strong>3 <\/strong><em>L\u2019avenir est dans la nuit<\/em>. Eva Demarelatrous, texte de Bertholt Brecht. Linogravures. 25 x 32 cm.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Etonnant parcours que celui d\u2019Eva Demarelatrous, cr\u00e9atrice qui&nbsp;vit et travaille \u00e0 Puyravault (Vend\u00e9e). Apr\u00e8s avoir \u00e9t\u00e9 \u00e9tudiante aux Beaux-arts de D\u00fcsseldorf, son mariage lui permet des s\u00e9jours en Alg\u00e9rie, en Allemagne et en France. C&rsquo;est \u00e0&nbsp; Bordeaux, T\u00fcbingen et Strasbourg qu&rsquo;elle fait \u00e9galement des \u00e9tudes de Lettres.&nbsp; D\u00e8s les ann\u00e9es 80, elle reprend une activit\u00e9 de peintre avec des confr\u00e8res comme Laubreton et Jacques Dominioni. Elle s\u2019initie \u00e0 la gravure dans l\u2019atelier de Fran\u00e7ois Verdier \u00e0 Niort, la typographie et les techniques du livre avec Djamel Meskache \u00e0 La Roche sur Yon. Parall\u00e8lement \u00e0 la peinture et \u00e0 la gravure, elle r\u00e9alise des livres d\u2019artistes et de dialogue, cr\u00e9e des \u0153uvres textiles de grands formats, participe \u00e0 des chemins d\u2019art et cr\u00e9e des jardins \u00e0 Chaumont sur Loire et au mus\u00e9e-parc du textile \u00e0 Wesserling en Alsace. Eva Demarelatrous&nbsp; se meut \u00ab&nbsp;<em>entre jubilation et douleur&nbsp;\u00bb<\/em>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/3-lavenir-est-dans-la-nuit-Eva-Demarelatrous.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"438\" data-attachment-id=\"7118\" data-permalink=\"https:\/\/alaincardenas.com\/blog\/concours-du-livre-dartiste-dissy-les-moulineaux-stephanie-ferrat-laureate-2023\/3-lavenir-est-dans-la-nuit-eva-demarelatrous\/\" data-orig-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/3-lavenir-est-dans-la-nuit-Eva-Demarelatrous.jpg?fit=800%2C600&amp;ssl=1\" data-orig-size=\"800,600\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 8&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1683827089&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.99&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"3, l&amp;rsquo;avenir est dans la nuit, Eva Demarelatrous\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/3-lavenir-est-dans-la-nuit-Eva-Demarelatrous.jpg?fit=584%2C438&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/3-lavenir-est-dans-la-nuit-Eva-Demarelatrous.jpg?resize=584%2C438&#038;ssl=1\" alt=\"\" class=\"wp-image-7118\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/3-lavenir-est-dans-la-nuit-Eva-Demarelatrous.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/3-lavenir-est-dans-la-nuit-Eva-Demarelatrous.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/3-lavenir-est-dans-la-nuit-Eva-Demarelatrous.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/3-lavenir-est-dans-la-nuit-Eva-Demarelatrous.jpg?resize=400%2C300&amp;ssl=1 400w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211;<strong>4 <\/strong><em>Manifeste de l\u2019ar\u00e9alisme<\/em>. Dominique Digeon.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019artiste a cr\u00e9\u00e9 de toutes pi\u00e8ces ce livre-\u00e9ph\u00e9m\u00e9ride. D\u00e9coupages et collages de fragments imprim\u00e9s d\u2019un texte d\u2019Andr\u00e9 Breton sont dispos\u00e9s sur un \u00e9ph\u00e9m\u00e9ride, accompagn\u00e9s d\u2019une mosa\u00efque de morceaux de cuir color\u00e9s sur le panneau de bois de l\u2019\u00e9ph\u00e9m\u00e9ride.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">N\u00e9 en 1959 \u00e0 Paris, l\u2019artiste vit et travaille en r\u00e9gion parisienne. Il commence \u00e0 peindre \u00e0 l\u2019\u00e2ge de 12 ans. Depuis 1991, il privil\u00e9gie une logique de s\u00e9ries. Inventeur d\u2019une technique de \u00ab\u2009papiers pel\u00e9s\u2009\u00bb, il travaille la relation espace-temps, repr\u00e9sentant le d\u00e9roul\u00e9 de parties d\u2019\u00e9checs en une seule image. Il est en 1992, le laur\u00e9at du prix de peinture Pierre Cardin. Deux ans plus tard, l\u2019obtention de l\u2019agr\u00e9gation d\u2019arts plastiques marque conjointement le d\u00e9but des d\u00e9tournements de photos, cartes et affiches. Parall\u00e8lement aux s\u00e9ries de tableaux il commence en 1999 un travail plastique sur le livre imprim\u00e9, enrichissant des ouvrages d\u2019\u00e9ditions courantes en objets pr\u00e9cieux qui entrent dans les collections nationales : biblioth\u00e8ques Kandinsky, Forney, Sainte Genevi\u00e8ve\u2026<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/4-manifeste-de-laeralisme-Dominique-Digeon.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"412\" data-attachment-id=\"7126\" data-permalink=\"https:\/\/alaincardenas.com\/blog\/concours-du-livre-dartiste-dissy-les-moulineaux-stephanie-ferrat-laureate-2023\/4-manifeste-de-laeralisme-dominique-digeon\/\" data-orig-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/4-manifeste-de-laeralisme-Dominique-Digeon.jpg?fit=1024%2C723&amp;ssl=1\" data-orig-size=\"1024,723\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 8&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1683827382&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.99&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.04&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"4, manifeste de l&amp;rsquo;ae\u0301ralisme, Dominique Digeon\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/4-manifeste-de-laeralisme-Dominique-Digeon.jpg?fit=584%2C412&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/4-manifeste-de-laeralisme-Dominique-Digeon.jpg?resize=584%2C412&#038;ssl=1\" alt=\"\" class=\"wp-image-7126\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/4-manifeste-de-laeralisme-Dominique-Digeon.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/4-manifeste-de-laeralisme-Dominique-Digeon.jpg?resize=300%2C212&amp;ssl=1 300w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/4-manifeste-de-laeralisme-Dominique-Digeon.jpg?resize=768%2C542&amp;ssl=1 768w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/4-manifeste-de-laeralisme-Dominique-Digeon.jpg?resize=425%2C300&amp;ssl=1 425w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211;<strong>5 <\/strong><em>b.a-ba. <\/em>Dbl-j. Texte de pH et conception plastique L\u00e9onore Fandol. Texte imprim\u00e9 sur plaques de verre serties dans des montures en m\u00e9tal. L\u2019\u0153uvre est accompagn\u00e9e d\u2019une montre \u00e0 gousset en \u00e9tat de marche avec sa cl\u00e9. 20 x 20 cm<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019originalit\u00e9 de&nbsp;[[&nbsp;dbl-j&nbsp;]], n\u00e9 \u00e0 l\u2019automne 1994, est de montrer le travail crois\u00e9 d\u2019un \u00e9crivain, L\u00e9onore Fandol, et d\u2019un&nbsp;&nbsp;peintre, pH, unissant ainsi l\u2019art litt\u00e9raire \u00e0 l\u2019art plastique. Issues des textes de l\u2019auteur, interpr\u00e9t\u00e9es alors en tant que mati\u00e8re, les cr\u00e9ations de&nbsp;[[&nbsp;dbl-j&nbsp;]], cr\u00e9ations de connivence par les deux artistes, trouvent leur expression dans des domaines diff\u00e9rents.&nbsp;\u0152uvres plastiques, livres objets et livres d\u2019artiste, ces cr\u00e9ations t\u00e9moignent d\u2019une volont\u00e9 d\u2019exp\u00e9rimentation&nbsp;o\u00f9 objets et mat\u00e9riaux d\u00e9tourn\u00e9s de leurs fonctions premi\u00e8res de m\u00eame que techniques traditionnelles&nbsp;ou innovantes agissent en tant que r\u00e9ponses au texte toujours pr\u00e9sent, nouvelle ou po\u00e9sie. La recherche de ce bin\u00f4me tend \u00e0 s\u2019\u00e9loigner des limites \u00e9tablies en p\u00e9n\u00e9trant les marges,&nbsp;en fouillant les ombres,&nbsp;[[dbl-j]], l\u2019\u0153uvre devient alors un lieu d\u2019\u00e9change suscitant un dialogue imm\u00e9diat avec tous les publics.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/5-b.a-ba-Leonore-Fandol-pH.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"584\" data-attachment-id=\"7130\" data-permalink=\"https:\/\/alaincardenas.com\/blog\/concours-du-livre-dartiste-dissy-les-moulineaux-stephanie-ferrat-laureate-2023\/5-b-a-ba-leonore-fandol-ph\/\" data-orig-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/5-b.a-ba-Leonore-Fandol-pH.jpg?fit=1024%2C1024&amp;ssl=1\" data-orig-size=\"1024,1024\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 8&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1683827584&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.99&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.04&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"5, b.a-ba, Le\u0301onore Fandol &amp;#038; pH\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/5-b.a-ba-Leonore-Fandol-pH.jpg?fit=584%2C584&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/5-b.a-ba-Leonore-Fandol-pH.jpg?resize=584%2C584&#038;ssl=1\" alt=\"\" class=\"wp-image-7130\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/5-b.a-ba-Leonore-Fandol-pH.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/5-b.a-ba-Leonore-Fandol-pH.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/5-b.a-ba-Leonore-Fandol-pH.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/5-b.a-ba-Leonore-Fandol-pH.jpg?resize=768%2C768&amp;ssl=1 768w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211;<strong>6 <\/strong><em>L\u2019existence est ailleurs<\/em>. St\u00e9phanie Ferrat. Texte de l\u2019artiste. Peintures avec adjonction de mati\u00e8res sur cartes marines.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">St\u00e9phanie Ferrat d\u00e9veloppe une \u0153uvre attentive aux oscillations du vivant, entre relev\u00e9s terriens et r\u00e9colte du ciel, qui interroge dans un geste fort et d\u00e9licat les sillons du monde. V\u00e9g\u00e9tation, animaux, roches, territoires, elle traverse les registres naturels dans un travail pictural fait de pigments, d\u2019empreintes et de traces qui est r\u00e9guli\u00e8rement expos\u00e9e en galerie (Sabine Puget, Unes Galerie, Univer, Pome Turbil\u2026). Elle est \u00e9galement l\u2019auteur de po\u00e8mes suspendus entre notation du r\u00e9el et palpitations sensibles, publi\u00e9s notamment par les \u00e9ditions La Lettre vol\u00e9e, Fissile ou L\u2019atelier La Feugraie. St\u00e9phanie Ferrat r\u00e9unit ses trajectoires artistiques et po\u00e9tiques depuis une vingtaine d\u2019ann\u00e9es avec la cr\u00e9ation d\u2019une maison d\u2019\u00e9dition de livres de bibliophilie, l<em>es mains<\/em>, o\u00f9 elle croise interventions picturales, textes et impression typographique. Une centaine de titres a paru \u00e0 ce jour, nourris de collaborations avec de nombreux auteurs parmi lesquels Ludovic Degroote, Jean-Louis Giovannoni, Erwann Roug\u00e9 et avec des plasticiens tels que Philippe Guitton, Leonardo Rosa ou Vincent Verdeguer.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/6-lexistence-est-ailleurs-Stephanie-Ferrat.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"513\" height=\"652\" data-attachment-id=\"7117\" data-permalink=\"https:\/\/alaincardenas.com\/blog\/concours-du-livre-dartiste-dissy-les-moulineaux-stephanie-ferrat-laureate-2023\/6-lexistence-est-ailleurs-stephanie-ferrat\/\" data-orig-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/6-lexistence-est-ailleurs-Stephanie-Ferrat.jpg?fit=513%2C652&amp;ssl=1\" data-orig-size=\"513,652\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 8&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1683828021&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.99&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"6, l&amp;rsquo;existence est ailleurs, Ste\u0301phanie Ferrat\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/6-lexistence-est-ailleurs-Stephanie-Ferrat.jpg?fit=513%2C652&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/6-lexistence-est-ailleurs-Stephanie-Ferrat.jpg?resize=513%2C652&#038;ssl=1\" alt=\"\" class=\"wp-image-7117\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/6-lexistence-est-ailleurs-Stephanie-Ferrat.jpg?w=513&amp;ssl=1 513w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/6-lexistence-est-ailleurs-Stephanie-Ferrat.jpg?resize=236%2C300&amp;ssl=1 236w\" sizes=\"auto, (max-width: 513px) 100vw, 513px\" \/><\/a><\/figure>\n<\/div>\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211;<strong>7 <\/strong><em>Fourrure de neige.<\/em> Magd\u00e9leine Ferru (Extraits de textes de Jules Verne). Livre r\u00e9alis\u00e9 en textile avec photographies sur canvas coton, calques et feuilles transparentes. Coffret en bois. 14 x 20 cm.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Magd\u00e9leine Ferru&nbsp;: <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Magd\u00e9leine -JustMagD- fran\u00e7aise, a choisi de faire ses \u00e9tudes de photographie \u00e0 Montr\u00e9al \u2026 Les livres l\u2019attirant de plus en plus, elle se forme au design, \u00e0 la mise en page et \u00e0 diverses techniques de reliures. Un \u00ab\u00a0livre sculpture\u00a0\u00bb Mus\u00e9e de Mariemont (2019) et une \u00ab\u00a0Reliure copte\u00a0\u00bb avec Marjon Mudde comptent parmi ses nombreuses cr\u00e9ations.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/7-Fourrure-de-neige-Magdeleine-Ferru.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"326\" data-attachment-id=\"7132\" data-permalink=\"https:\/\/alaincardenas.com\/blog\/concours-du-livre-dartiste-dissy-les-moulineaux-stephanie-ferrat-laureate-2023\/7-fourrure-de-neige-magdeleine-ferru\/\" data-orig-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/7-Fourrure-de-neige-Magdeleine-Ferru.jpg?fit=1011%2C565&amp;ssl=1\" data-orig-size=\"1011,565\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 8&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1683828225&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.99&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.04&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"7, Fourrure de neige, Magde\u0301leine Ferru\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/7-Fourrure-de-neige-Magdeleine-Ferru.jpg?fit=584%2C326&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/7-Fourrure-de-neige-Magdeleine-Ferru.jpg?resize=584%2C326&#038;ssl=1\" alt=\"\" class=\"wp-image-7132\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/7-Fourrure-de-neige-Magdeleine-Ferru.jpg?w=1011&amp;ssl=1 1011w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/7-Fourrure-de-neige-Magdeleine-Ferru.jpg?resize=300%2C168&amp;ssl=1 300w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/7-Fourrure-de-neige-Magdeleine-Ferru.jpg?resize=768%2C429&amp;ssl=1 768w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/7-Fourrure-de-neige-Magdeleine-Ferru.jpg?resize=500%2C279&amp;ssl=1 500w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211;<strong>8 <\/strong><em>Chemins \u00e9perdus. <\/em>Anne Lascoux. Inspir\u00e9 de chansons d\u2019Antonio Machado. Leporello asym\u00e9trique \u00e0 g\u00e9om\u00e9trie variable. Se range dans un boitier \u00e0 couvercle aimant\u00e9. 7 x 7 cm.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/8-chemins-eperdus-Anne-Lascoux.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"438\" data-attachment-id=\"7128\" data-permalink=\"https:\/\/alaincardenas.com\/blog\/concours-du-livre-dartiste-dissy-les-moulineaux-stephanie-ferrat-laureate-2023\/8-chemins-eperdus-anne-lascoux\/\" data-orig-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/8-chemins-eperdus-Anne-Lascoux.jpg?fit=1024%2C768&amp;ssl=1\" data-orig-size=\"1024,768\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 8&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1683828323&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.99&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.058823529411765&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"8, chemins e\u0301perdus, Anne Lascoux\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/8-chemins-eperdus-Anne-Lascoux.jpg?fit=584%2C438&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/8-chemins-eperdus-Anne-Lascoux.jpg?resize=584%2C438&#038;ssl=1\" alt=\"\" class=\"wp-image-7128\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/8-chemins-eperdus-Anne-Lascoux.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/8-chemins-eperdus-Anne-Lascoux.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/8-chemins-eperdus-Anne-Lascoux.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/8-chemins-eperdus-Anne-Lascoux.jpg?resize=400%2C300&amp;ssl=1 400w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211;<strong>9 <\/strong><em>Vivre l\u00e0-ailleurs<\/em>. Viviane Michel. D\u2019apr\u00e8s un po\u00e8me de Rousselot. Leporello emboit\u00e9 dans un coffret en forme de maison. Illustration et texte manuscrit aux crayons de couleurs. 16 x 7 cm.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Viviane Michel a fait ses \u00e9tudes \u00e0 l\u2019\u00e9cole des Beaux-Arts de Toulouse o\u00f9 elle a partiqu\u00e9&nbsp; diff\u00e9rentes techniques d\u2019expression (peinture, dessin, photographie, pliage,&nbsp;photogravures\u2026) qu\u2019elle poursuit encore aujourd\u2019hui. La singularit\u00e9 de ses ouvrages s\u2019articule autour de ces&nbsp;techniques&nbsp;qui s\u2019entrecroisent avec la&nbsp;finesse du trac\u00e9 de son dessin. Artiste ind\u00e9pendante depuis 2005, elle vit et travaille en Mayenne.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/9-vivre-la-ailleurs-Viviane-Michel.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"438\" data-attachment-id=\"7127\" data-permalink=\"https:\/\/alaincardenas.com\/blog\/concours-du-livre-dartiste-dissy-les-moulineaux-stephanie-ferrat-laureate-2023\/9-vivre-la-ailleurs-viviane-michel\/\" data-orig-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/9-vivre-la-ailleurs-Viviane-Michel.jpg?fit=1024%2C768&amp;ssl=1\" data-orig-size=\"1024,768\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 8&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1683828494&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.99&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.04&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"9, vivre la\u0300-ailleurs, Viviane Michel\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/9-vivre-la-ailleurs-Viviane-Michel.jpg?fit=584%2C438&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/9-vivre-la-ailleurs-Viviane-Michel.jpg?resize=584%2C438&#038;ssl=1\" alt=\"\" class=\"wp-image-7127\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/9-vivre-la-ailleurs-Viviane-Michel.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/9-vivre-la-ailleurs-Viviane-Michel.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/9-vivre-la-ailleurs-Viviane-Michel.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/9-vivre-la-ailleurs-Viviane-Michel.jpg?resize=400%2C300&amp;ssl=1 400w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211;<strong>10 <\/strong><em>Ziran. <\/em>Marjon Mudde. Texte de l\u2019artiste et un extrait du Tao Te King. Typographie au plomb. Eaux forte, linogravures, dessin, collage, broderie, couture. Papier v\u00e9g\u00e9tal, papier marbr\u00e9, papier n\u00e9palais sur pages en textiles. Gaze teinte, \u00e9l\u00e9ments de r\u00e9cup\u00e9ration en m\u00e9tal. 20 x 20 cm.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Marjon Mudde&nbsp;: <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Artiste polyvalente, \u00e0 l\u2019esprit d\u2019exp\u00e9rimentation infatigable, Marjon Mudde aime revisiter les techniques anciennes, pour les employer \u2013 parfois d\u2019une fa\u00e7on inattendue \u2013 dans ses gravures, ses livres d\u2019artiste ou ses c\u00e9ramiques. Elle n\u2019h\u00e9site pas non plus \u00e0 m\u00e9langer les genres : du textile ou de la c\u00e9ramique dans ses livres, du carton pour graver, du bois et du m\u00e9tal dans les reliures\u2026Ses cr\u00e9ations sont r\u00e9guli\u00e8rement expos\u00e9es et collectionn\u00e9es par des institutions et des particuliers, en France ou \u00e0 l\u2019\u00e9tranger.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/10-zaran-Marjon-Mudde.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"779\" data-attachment-id=\"7120\" data-permalink=\"https:\/\/alaincardenas.com\/blog\/concours-du-livre-dartiste-dissy-les-moulineaux-stephanie-ferrat-laureate-2023\/10-zaran-marjon-mudde\/\" data-orig-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/10-zaran-Marjon-Mudde.jpg?fit=600%2C800&amp;ssl=1\" data-orig-size=\"600,800\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 8&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1683828723&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.99&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.05&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"10, zaran, Marjon Mudde\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/10-zaran-Marjon-Mudde.jpg?fit=584%2C779&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/10-zaran-Marjon-Mudde.jpg?resize=584%2C779&#038;ssl=1\" alt=\"\" class=\"wp-image-7120\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/10-zaran-Marjon-Mudde.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/10-zaran-Marjon-Mudde.jpg?resize=225%2C300&amp;ssl=1 225w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211;<strong>11 <\/strong><em>A contre-emploi. <\/em>Catherine Pomper. Texte de l\u2019artiste. Collages, peintures et texte manuscrit.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/11-a-contre-emploi-Catherine-Pomper.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"438\" data-attachment-id=\"7119\" data-permalink=\"https:\/\/alaincardenas.com\/blog\/concours-du-livre-dartiste-dissy-les-moulineaux-stephanie-ferrat-laureate-2023\/11-a-contre-emploi-catherine-pomper\/\" data-orig-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/11-a-contre-emploi-Catherine-Pomper.jpg?fit=800%2C600&amp;ssl=1\" data-orig-size=\"800,600\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 8&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1683829017&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.99&quot;,&quot;iso&quot;:&quot;64&quot;,&quot;shutter_speed&quot;:&quot;0.058823529411765&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"11, a\u0300 contre-emploi, Catherine Pomper\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/11-a-contre-emploi-Catherine-Pomper.jpg?fit=584%2C438&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/11-a-contre-emploi-Catherine-Pomper.jpg?resize=584%2C438&#038;ssl=1\" alt=\"\" class=\"wp-image-7119\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/11-a-contre-emploi-Catherine-Pomper.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/11-a-contre-emploi-Catherine-Pomper.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/11-a-contre-emploi-Catherine-Pomper.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/11-a-contre-emploi-Catherine-Pomper.jpg?resize=400%2C300&amp;ssl=1 400w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211;<strong>12 <\/strong><em>Aliunde. <\/em>Rachel Rivi\u00e8re. Texte de l\u2019artiste. Photographies sur papier de riz. Marouflage sur papier Fabriano. Gaufrage \u00e0 l\u2019encre noire. Texte imprim\u00e9 au tampon. 15 x 15 cm. Boitier avec sur le dessus, une photographie sur papier de riz maroufl\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rach\u00e8le Rivi\u00e8re&nbsp;:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u00e9ramiste plasticienne, Rach\u00e8le Rivi\u00e8re explore les traces visibles et invisibles du souvenir, qu\u2019elle esth\u00e9tise avec une grande force graphique. Ces formes \u00e9pur\u00e9es et famili\u00e8res contrastent avec la densit\u00e9 myst\u00e9rieuse de ces impressions photographiques en noir et blanc. Les images semblent surgir \u00e0 la surface de ces objets t\u00e9moins de notre quotidien, ressuscitant les fragments oubli\u00e9s d\u2019une m\u00e9moire d\u00e9faillante. Pour quel motif ? La relativit\u00e9 du temps, la fragilit\u00e9 de la m\u00e9moire sont des motifs constants de la r\u00e9flexion de cette arch\u00e9ologue de l\u2019\u00e2me.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/12-aliunde-Rachel-Riviere.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"347\" data-attachment-id=\"7121\" data-permalink=\"https:\/\/alaincardenas.com\/blog\/concours-du-livre-dartiste-dissy-les-moulineaux-stephanie-ferrat-laureate-2023\/12-aliunde-rachel-riviere\/\" data-orig-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/12-aliunde-Rachel-Riviere.jpg?fit=1024%2C609&amp;ssl=1\" data-orig-size=\"1024,609\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 8&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1683829089&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.99&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"12, aliunde, Rachel Rivie\u0300re\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/12-aliunde-Rachel-Riviere.jpg?fit=584%2C347&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/12-aliunde-Rachel-Riviere.jpg?resize=584%2C347&#038;ssl=1\" alt=\"\" class=\"wp-image-7121\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/12-aliunde-Rachel-Riviere.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/12-aliunde-Rachel-Riviere.jpg?resize=300%2C178&amp;ssl=1 300w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/12-aliunde-Rachel-Riviere.jpg?resize=768%2C457&amp;ssl=1 768w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/12-aliunde-Rachel-Riviere.jpg?resize=500%2C297&amp;ssl=1 500w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211;<strong>13 <\/strong><em>Je serai l\u00e0. <\/em>Patricia Sarne. Texte original de Flora Delalande. Peintures et gaufrages au carborundum. 20 x 28 cm.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Patricia Sarne est coutumi\u00e8re d\u2019une pratique des arts (danse classique, guitare, piano, peinture), qui a impr\u00e9gn\u00e9 ses premi\u00e8res ann\u00e9es. Apr\u00e8s le dipl\u00f4me de l&rsquo;Ecole Sup\u00e9rieure des Arts Appliqu\u00e9s Dup\u00e9err\u00e9 en 1981, o\u00f9 elle aborde les techniques d&rsquo;art mural, la photographie et la restauration de tableaux, Patricia Sarne travaille comme coloriste dans une agence d&rsquo;architecture et de recherches chromatiques. Puis elle se consacre \u00e0 la peinture en des th\u00e8mes toujours renouvel\u00e9s (Ombres, Reflets, Lumi\u00e8res d&rsquo;hiver, Cosmos, Galets, Torrents, Musique et Danse, Jours, Swing calligraphies, El\u00e9ments, Saisons, Danse des calligraphies, lumi\u00e8res et ombres v\u00e9g\u00e9tales, Aqua&#8230;), qu\u00eate de la permanence \u00e9ph\u00e9m\u00e8re. D\u00e8s 1980, le dessin calligraphique au pinceau et \u00e0 l&rsquo;encre de chine, d&rsquo;apr\u00e8s mod\u00e8les en mouvement, est une part importante de sa recherche. (a\u00efki-do , danse contemporaine, vols de mouettes, musique)\u2026 Depuis 2012, ses livres d\u2019artiste ont recours aux techniques les plus diverses&nbsp;: gravures, encres, collages, photos et po\u00e9sies.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/07\/Patricia-Sarne_Je-serai-la_1-1.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"476\" height=\"480\" data-attachment-id=\"7382\" data-permalink=\"https:\/\/alaincardenas.com\/blog\/concours-du-livre-dartiste-dissy-les-moulineaux-stephanie-ferrat-laureate-2023\/patricia-sarne_je-serai-la_1-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/07\/Patricia-Sarne_Je-serai-la_1-1.jpg?fit=476%2C480&amp;ssl=1\" data-orig-size=\"476,480\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1689002049&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Patricia-Sarne_Je-serai-la_1-1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/07\/Patricia-Sarne_Je-serai-la_1-1.jpg?fit=476%2C480&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/07\/Patricia-Sarne_Je-serai-la_1-1.jpg?resize=476%2C480&#038;ssl=1\" alt=\"\" class=\"wp-image-7382\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/07\/Patricia-Sarne_Je-serai-la_1-1.jpg?w=476&amp;ssl=1 476w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/07\/Patricia-Sarne_Je-serai-la_1-1.jpg?resize=298%2C300&amp;ssl=1 298w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/07\/Patricia-Sarne_Je-serai-la_1-1.jpg?resize=150%2C150&amp;ssl=1 150w\" sizes=\"auto, (max-width: 476px) 100vw, 476px\" \/><\/a><\/figure>\n<\/div>\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211;<strong>14 <\/strong><em>Crois\u00e9e des passages. <\/em>Sylvie Schambill. Texte d\u2019Agn\u00e8s Adda. Collages, peintures c\u00e9ramique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sylvie Schambill&nbsp;explore les ressources de multiples m\u00e9diums pour r\u00e9v\u00e9ler mes mondes int\u00e9rieurs, mes chemins de vie et ensuite en partager la m\u00e9moire&nbsp;\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/14-croisee-des-passages-Sylvie-Schambill.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"339\" data-attachment-id=\"7123\" data-permalink=\"https:\/\/alaincardenas.com\/blog\/concours-du-livre-dartiste-dissy-les-moulineaux-stephanie-ferrat-laureate-2023\/14-croisee-des-passages-sylvie-schambill\/\" data-orig-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/14-croisee-des-passages-Sylvie-Schambill.jpg?fit=1024%2C595&amp;ssl=1\" data-orig-size=\"1024,595\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 8&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1683830031&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.99&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"14, croise\u0301e des passages, Sylvie Schambill\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/14-croisee-des-passages-Sylvie-Schambill.jpg?fit=584%2C339&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/14-croisee-des-passages-Sylvie-Schambill.jpg?resize=584%2C339&#038;ssl=1\" alt=\"\" class=\"wp-image-7123\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/14-croisee-des-passages-Sylvie-Schambill.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/14-croisee-des-passages-Sylvie-Schambill.jpg?resize=300%2C174&amp;ssl=1 300w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/14-croisee-des-passages-Sylvie-Schambill.jpg?resize=768%2C446&amp;ssl=1 768w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/14-croisee-des-passages-Sylvie-Schambill.jpg?resize=500%2C291&amp;ssl=1 500w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211;<strong>15<\/strong> <em>L\u2019enfer<\/em>. Marc Vernier. Papiers structur\u00e9s. Couverture en m\u00e9tal mordu \u00e0 l\u2019acide. 30 x 21 cm.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La complexit\u00e9 de la cr\u00e9ation de Marc Vernier&nbsp;se construit sur des structures simples.&nbsp;Il rappelle son approche dans le texte suivant&nbsp;: \u00ab&nbsp;pour chaque artiste, il existe un travail \u00e0 d\u00e9couvrir par la sensibilit\u00e9 de celui qui le regarde en dehors des jugements critiques ou intellectuels\u2026 \u200b Le travail de plasticien est une recherche d\u2019harmonie avec des jeux de mati\u00e8res (bois, m\u00e9tal, ardoise, papier) et une juste r\u00e9partition de diff\u00e9rentes intensit\u00e9s de noirs, de bruns, de blancs. Inspir\u00e9 des jardins japonais ou du Bauhaus, mes tableaux et mes gravures sont le r\u00e9sultat d\u2019une r\u00e9flexion approfondie et d\u2019une r\u00e9alisation exigeante. Leurs formats identiques forment un ensemble coh\u00e9rent. Mes livres sculptures, toutes des pi\u00e8ces uniques, sont le prolongement en volume de ma peinture&nbsp;\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/15-lenfer-Marc-Vernier.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"685\" data-attachment-id=\"7124\" data-permalink=\"https:\/\/alaincardenas.com\/blog\/concours-du-livre-dartiste-dissy-les-moulineaux-stephanie-ferrat-laureate-2023\/15-lenfer-marc-vernier\/\" data-orig-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/15-lenfer-Marc-Vernier.jpg?fit=873%2C1024&amp;ssl=1\" data-orig-size=\"873,1024\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 8&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1683830168&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.99&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"15, l&amp;rsquo;enfer, Marc Vernier\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/15-lenfer-Marc-Vernier.jpg?fit=584%2C685&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/15-lenfer-Marc-Vernier.jpg?resize=584%2C685&#038;ssl=1\" alt=\"\" class=\"wp-image-7124\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/15-lenfer-Marc-Vernier.jpg?w=873&amp;ssl=1 873w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/15-lenfer-Marc-Vernier.jpg?resize=256%2C300&amp;ssl=1 256w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/15-lenfer-Marc-Vernier.jpg?resize=768%2C901&amp;ssl=1 768w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;NB:&nbsp; le compte rendu reprend partiellement les biographies publi\u00e9es ant\u00e9rieurement.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(*) Marie-Paule Peronnet est sp\u00e9cialiste de l\u2019histoire du livre, notamment du livre de cr\u00e9ation et d\u2019artiste et de la bibliologie moderne et contemporaine occidentale, l\u2019autrice est collaboratrice r\u00e9guli\u00e8re \u00e0 la revue AML.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(**) Fr\u00e9d\u00e9ric Harranger, musicien et cr\u00e9ateur, est en charge du fonds de livres d\u2019artistes \u00e0 la m\u00e9diath\u00e8que d\u2019Issy-les-Moulineaux.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Compte-rendu. par Marie-Paule Peronnet (*) Depuis six ans, cette manifestation met l\u2019accent sur la pluralit\u00e9 du type de cr\u00e9ation \u00e0 la fois r\u00e9cent et historique que constitue le livre d\u2019artiste. Apparu en Occident vers le 19e si\u00e8cle selon certains, en &hellip; <a href=\"https:\/\/alaincardenas.com\/blog\/concours-du-livre-dartiste-dissy-les-moulineaux-stephanie-ferrat-laureate-2023\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[27,42,21],"tags":[45,8,46,39],"class_list":["post-7096","post","type-post","status-publish","format-standard","hentry","category-compte-rendu","category-europe","category-evenement","tag-art","tag-art-contemporain","tag-arts-appliques","tag-exposition"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8Mijt-1Qs","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":8017,"url":"https:\/\/alaincardenas.com\/blog\/concours-du-livre-dartiste-dissy-les-moulineaux-marc-vernier-laureat-2024\/","url_meta":{"origin":7096,"position":0},"title":"Concours du livre d\u2019artiste d\u2019Issy-les-Moulineaux, Marc Vernier, laur\u00e9at 2024.","author":"admin","date":"2024-05-30","format":false,"excerpt":"Compte-rendu. par Christophe Comentale et Fr\u00e9d\u00e9ric Harranger Depuis sept ans, cette manifestation met l\u2019accent sur la pluralit\u00e9 du type de cr\u00e9ation \u00e0 la fois r\u00e9cent et historique que constitue le livre d\u2019artiste. Comme cela \u00e9tait signal\u00e9 dans le compte-rendu de l\u2019ann\u00e9e 2023, \u00ab\u00a0Apparu en Occident vers le 19e\u00a0si\u00e8cle selon certains,\u2026","rel":"","context":"Dans &quot;Compte-rendu&quot;","block_context":{"text":"Compte-rendu","link":"https:\/\/alaincardenas.com\/blog\/category\/compte-rendu\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2024\/05\/image_67364353-scaled.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2024\/05\/image_67364353-scaled.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2024\/05\/image_67364353-scaled.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2024\/05\/image_67364353-scaled.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2024\/05\/image_67364353-scaled.jpg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2024\/05\/image_67364353-scaled.jpg?resize=1400%2C800 4x"},"classes":[]},{"id":6308,"url":"https:\/\/alaincardenas.com\/blog\/a-propos-du-laureat-du-concours-2022-du-livre-dartiste-de-la-ville-dissy-les-moulineaux-ombre-et-lumiere-du-tarot-chronique-dun-monde-disparu\/","url_meta":{"origin":7096,"position":1},"title":"A propos du \u2026  Laur\u00e9at du Concours 2022 du livre d\u2019artiste de la ville d\u2019Issy-les-Moulineaux, \u00ab\u00a0Ombre et lumi\u00e8re du tarot. Chronique d\u2019un monde disparu\u00a0\u00bb.","author":"admin","date":"2022-06-09","format":false,"excerpt":"par Fr\u00e9d\u00e9ric Harranger et Christophe Comentale Parall\u00e8lement \u00e0 la num\u00e9risation sociale, vaste processus technico-politique qui permet d\u2019ores et d\u00e9j\u00e0 de simplifier de fa\u00e7on harmonieuse \u2014 le plus souvent \u2014 et autoritaire \u2014 aussi \u2014 les transactions du quotidien, le go\u00fbt et les envies continuent d\u2019induire une production artistique dont le\u2026","rel":"","context":"Dans &quot;Am\u00e9rique latine&quot;","block_context":{"text":"Am\u00e9rique latine","link":"https:\/\/alaincardenas.com\/blog\/category\/amerique-latine\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2022\/06\/1651733954201-copie-BD.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2022\/06\/1651733954201-copie-BD.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2022\/06\/1651733954201-copie-BD.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2022\/06\/1651733954201-copie-BD.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":7942,"url":"https:\/\/alaincardenas.com\/blog\/archipel-sculptures-et-dessins-de-jean-anguera\/","url_meta":{"origin":7096,"position":2},"title":"ARCHIPEL, sculptures et dessins de Jean Anguera","author":"admin","date":"2024-04-21","format":false,"excerpt":"L\u2019exposition Archipel, mus\u00e9e de la carte \u00e0 jouer et m\u00e9diath\u00e8que d\u2019Issy-les-Moulineaux, du 22 novembre 2023 au 11 f\u00e9vrier 2024. Fils d\u2019un p\u00e8re statisticien chercheur en m\u00e9decine, Jordi Anguera, d\u2019une m\u00e8re sculptrice, Pierrette Gargallo et petit-fils du sculpteur aragonais\u00a0Pablo Gargallo, Jean Anguera (1953, Paris) affirme tr\u00e8s t\u00f4t son go\u00fbt pour le\u2026","rel":"","context":"Dans &quot;Compte-rendu&quot;","block_context":{"text":"Compte-rendu","link":"https:\/\/alaincardenas.com\/blog\/category\/compte-rendu\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2024\/04\/Anguera-Jean-Neige-a.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7011,"url":"https:\/\/alaincardenas.com\/blog\/a-propos-dune-installation-de-catherine-pomper-amerrir-a-loree-de-ses-reves\/","url_meta":{"origin":7096,"position":3},"title":"A propos d\u2019une installation de Catherine Pomper, Amerrir \u00e0 l\u2019or\u00e9e de ses r\u00eaves","author":"admin","date":"2023-04-29","format":false,"excerpt":"par Christophe Comentale et Fr\u00e9d\u00e9ric Harranger Dans le silence feutr\u00e9 et modul\u00e9 de son atelier-jardin de Saint-Cyr l\u2019\u00c9cole, Catherine Pomper livre de temps \u00e0 autre \u00e0 un public de collectionneurs et de curieux des images qui vont et viennent parmi des pans de son imaginaire. Ainsi en va-t-il de cette\u2026","rel":"","context":"Dans &quot;Europe&quot;","block_context":{"text":"Europe","link":"https:\/\/alaincardenas.com\/blog\/category\/europe\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/04\/illustration-5.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/04\/illustration-5.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/04\/illustration-5.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/04\/illustration-5.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":6245,"url":"https:\/\/alaincardenas.com\/blog\/un-salon-du-livre-dartiste-singulier-a-nevers\/","url_meta":{"origin":7096,"position":4},"title":"Un salon du livre d\u2019artiste singulier \u00e0 Nevers","author":"admin","date":"2022-05-08","format":false,"excerpt":"par Marie-Paule Peronnet L\u2019\u00e9t\u00e9 est propice aux manifestations artistiques, les \u0153uvres sont davantage sollicit\u00e9es \u00e0 la curiosit\u00e9 ordinaire. Souhaitons que \u00e7a dure. Tel doit \u00eatre l\u2019avis de Marc Vernier, commissaire g\u00e9n\u00e9ral du Salon du livre d\u2019artiste et des m\u00e9tiers du livre, qui a, apr\u00e8s diff\u00e9rents reports, pu rassembler une quarantaine\u2026","rel":"","context":"Dans &quot;Europe&quot;","block_context":{"text":"Europe","link":"https:\/\/alaincardenas.com\/blog\/category\/europe\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2022\/05\/1651929978349-BD.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4627,"url":"https:\/\/alaincardenas.com\/blog\/le-livre-dartiste-un-livre-qui-nest-pas-un-livre\/","url_meta":{"origin":7096,"position":5},"title":"Le livre d\u2019artiste, un livre qui n\u2019est pas un livre","author":"admin","date":"2020-02-01","format":false,"excerpt":"Institut catholique de Paris,\u00a0Biblioth\u00e8que de Fels, Le livre d\u2019artiste, un livre qui n\u2019est pas un livre.\u00a0Du 5 au 28 f\u00e9vrier 2020, du lundi au vendredi, de 9h \u00e0 19h. Commissariat de Guillaume Boyer, Alain Cardenas-Castro et Christophe Comentale Quelques mots avant de tourner autour des vitrines Comme le rappelle l\u2019un\u2026","rel":"","context":"Dans &quot;Asie&quot;","block_context":{"text":"Asie","link":"https:\/\/alaincardenas.com\/blog\/category\/asie\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/02\/sales-b%C3%AAtes-MBM.png?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/posts\/7096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/comments?post=7096"}],"version-history":[{"count":12,"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/posts\/7096\/revisions"}],"predecessor-version":[{"id":7385,"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/posts\/7096\/revisions\/7385"}],"wp:attachment":[{"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/media?parent=7096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/categories?post=7096"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/tags?post=7096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}