{"id":5118,"date":"2020-06-27T18:32:00","date_gmt":"2020-06-27T16:32:00","guid":{"rendered":"https:\/\/alaincardenas.com\/blog\/?p=5118"},"modified":"2025-02-25T22:31:19","modified_gmt":"2025-02-25T21:31:19","slug":"portraits-dhier-et-de-demain-3-de-la-peinture-murale-peruvienne-a-propos-de-deux-oeuvres-tadeo-escalante-muraliste-du-sud-andin-1","status":"publish","type":"post","link":"https:\/\/alaincardenas.com\/blog\/portraits-dhier-et-de-demain-3-de-la-peinture-murale-peruvienne-a-propos-de-deux-oeuvres-tadeo-escalante-muraliste-du-sud-andin-1\/","title":{"rendered":"Portraits d\u2019hier et de demain (3)  De la peinture murale p\u00e9ruvienne :  \u00c0 propos de deux \u0153uvres de Tadeo Escalante, muraliste du Sud-andin (1)"},"content":{"rendered":"<p>Rapport\u00a0succinct d&rsquo;une mission de recherche men\u00e9e en octobre 2019 dans la r\u00e9gion de Cuzco. Durant ce s\u00e9jour de recherche, l&rsquo;auteur a pu fournir un ensemble de photographies in\u00e9dites. L&rsquo;acc\u00e8s parfois difficile aux lieux n&rsquo;a pas pu permettre une qualit\u00e9 toujours identique de ces documents. Ils sont compl\u00e9t\u00e9s par une iconographie justifi\u00e9e dans la partie bibliographique.<\/p>\n<p>par Alain Cardenas-Castro<\/p>\n<p>En Am\u00e9rique latine, la peinture murale est souvent associ\u00e9e au mouvement constitu\u00e9 par les peintres muralistes mexicains<a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a>. Toutefois, cette technique a \u00e9t\u00e9 utilis\u00e9e couramment au P\u00e9rou. Depuis les premi\u00e8res grottes orn\u00e9es, comme celle de Toquepala<a href=\"#_ftn2\" name=\"_ftnref2\">[2]<\/a> (ill. 1), jusqu\u2019aux r\u00e9alisations plus r\u00e9centes des peintres p\u00e9ruviens, Carlos Quispez Asin (1900-1983) (ill. 2), Juan Bravo Vizcarra (1922-2016) (ill. 3) ou Jorge Chirinos (1968) (ill. 4), la peinture murale au P\u00e9rou s\u2019est renouvel\u00e9e continuellement.<\/p>\n<p><!--more--><\/p>\n<p>Contrairement aux \u0153uvres majoritairement r\u00e9alis\u00e9es dans l\u2019espace public, certaines \u0153uvres murales de l&rsquo;espace priv\u00e9, p\u00e9ruviennes, sont astreintes \u00e0 des conditions particuli\u00e8res de cr\u00e9ation. C\u2019est le cas des peintures murales qui ont affirm\u00e9 un nationalisme inca durant la derni\u00e8re d\u00e9cennie du XIX<sup>e<\/sup> si\u00e8cle. En effet, afin d\u2019\u00e9chapper \u00e0 la r\u00e9pression du pouvoir colonial espagnol \u00e0 l\u2019encontre du sentiment identitaire inca\u00efque qui a perdur\u00e9 apr\u00e8s la chute de l\u2019Empire inca, elles ont \u00e9t\u00e9 r\u00e9alis\u00e9es dans des endroits incongrus.<\/p>\n<p>Tadeo Escalante fait partie des peintres qui ont \u0153uvr\u00e9 \u2014 \u00e0 cet art mural p\u00e9ruvien soustrait au regard du plus grand nombre \u2014 dans des temples, des maisons ou des moulins.<\/p>\n<div id=\"attachment_5120\" style=\"width: 187px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/01-grotte-Toquepala-P%C3%A9rou.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5120\" data-attachment-id=\"5120\" data-permalink=\"https:\/\/alaincardenas.com\/blog\/portraits-dhier-et-de-demain-3-de-la-peinture-murale-peruvienne-a-propos-de-deux-oeuvres-tadeo-escalante-muraliste-du-sud-andin-1\/01-grotte-toquepala-perou\/\" data-orig-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/01-grotte-Toquepala-P%C3%A9rou.jpg?fit=417%2C468&amp;ssl=1\" data-orig-size=\"417,468\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"01 grotte Toquepala P\u00e9rou\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/01-grotte-Toquepala-P%C3%A9rou.jpg?fit=417%2C468&amp;ssl=1\" class=\"wp-image-5120\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/01-grotte-Toquepala-P%C3%A9rou.jpg?resize=177%2C198&#038;ssl=1\" alt=\"\" width=\"177\" height=\"198\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/01-grotte-Toquepala-P%C3%A9rou.jpg?resize=267%2C300&amp;ssl=1 267w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/01-grotte-Toquepala-P%C3%A9rou.jpg?w=417&amp;ssl=1 417w\" sizes=\"auto, (max-width: 177px) 100vw, 177px\" \/><\/a><p id=\"caption-attachment-5120\" class=\"wp-caption-text\">(ill.\u00a01) Peintures pari\u00e9tales, grotte de Toquepala, Tacna, P\u00e9rou.<\/p><\/div>\n<div id=\"attachment_5121\" style=\"width: 233px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/02-Capture-d%E2%80%99%C3%A9cran-2020-06-09-%C3%A0-13.44.49.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5121\" data-attachment-id=\"5121\" data-permalink=\"https:\/\/alaincardenas.com\/blog\/portraits-dhier-et-de-demain-3-de-la-peinture-murale-peruvienne-a-propos-de-deux-oeuvres-tadeo-escalante-muraliste-du-sud-andin-1\/02-capture-decran-2020-06-09-a-13-44-49\/\" data-orig-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/02-Capture-d%E2%80%99%C3%A9cran-2020-06-09-%C3%A0-13.44.49.jpg?fit=684%2C508&amp;ssl=1\" data-orig-size=\"684,508\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"02 Capture d\u2019\u00e9cran 2020-06-09 \u00e0 13.44.49\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/02-Capture-d%E2%80%99%C3%A9cran-2020-06-09-%C3%A0-13.44.49.jpg?fit=584%2C434&amp;ssl=1\" class=\"wp-image-5121\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/02-Capture-d%E2%80%99%C3%A9cran-2020-06-09-%C3%A0-13.44.49.jpg?resize=223%2C168&#038;ssl=1\" alt=\"\" width=\"223\" height=\"168\" \/><\/a><p id=\"caption-attachment-5121\" class=\"wp-caption-text\">(ill. 2) Carlos Qu\u00edzpez As\u00edn, Mural La\u00a0mineria\u00a0La mine (1944), Universidad de ingenieria, Lima, P\u00e9rou<\/p><\/div>\n<div id=\"attachment_5123\" style=\"width: 806px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/04-DSC_3906_059.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5123\" data-attachment-id=\"5123\" data-permalink=\"https:\/\/alaincardenas.com\/blog\/portraits-dhier-et-de-demain-3-de-la-peinture-murale-peruvienne-a-propos-de-deux-oeuvres-tadeo-escalante-muraliste-du-sud-andin-1\/04-dsc_3906_059\/\" data-orig-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/04-DSC_3906_059.jpg?fit=796%2C394&amp;ssl=1\" data-orig-size=\"796,394\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;F3311&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1520963019&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.5&quot;,&quot;iso&quot;:&quot;111&quot;,&quot;shutter_speed&quot;:&quot;0.0088710008624584&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"04 DSC_3906_059\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;(ill. 7)&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/04-DSC_3906_059.jpg?fit=584%2C289&amp;ssl=1\" class=\"wp-image-5123 size-full\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/04-DSC_3906_059.jpg?resize=584%2C289&#038;ssl=1\" alt=\"\" width=\"584\" height=\"289\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/04-DSC_3906_059.jpg?w=796&amp;ssl=1 796w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/04-DSC_3906_059.jpg?resize=300%2C148&amp;ssl=1 300w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/04-DSC_3906_059.jpg?resize=768%2C380&amp;ssl=1 768w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/04-DSC_3906_059.jpg?resize=500%2C247&amp;ssl=1 500w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a><p id=\"caption-attachment-5123\" class=\"wp-caption-text\">(ill.3) Juan Bravo, <strong><em>Historia del qosqo<\/em><\/strong>\u00a0Histoire du Cusco (1992), Cusco, P\u00e9rou<\/p><\/div>\n<div id=\"attachment_5122\" style=\"width: 910px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/03-Jorge-DSC_1708-recadre-BD.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5122\" data-attachment-id=\"5122\" data-permalink=\"https:\/\/alaincardenas.com\/blog\/portraits-dhier-et-de-demain-3-de-la-peinture-murale-peruvienne-a-propos-de-deux-oeuvres-tadeo-escalante-muraliste-du-sud-andin-1\/03-jorge-dsc_1708-recadre-bd\/\" data-orig-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/03-Jorge-DSC_1708-recadre-BD.jpg?fit=900%2C341&amp;ssl=1\" data-orig-size=\"900,341\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;F3311&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1541425285&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.5&quot;,&quot;iso&quot;:&quot;111&quot;,&quot;shutter_speed&quot;:&quot;0.0058409999554122&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"03 Jorge DSC_1708 &amp;#8211; recadre BD\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Ci-dessous, de gauche \u00e0 droite. (ill.\u00a04) Jorge Luis Chirinos V\u00e1squez, Pass\u00e9, pr\u00e9sent et futur de la M\u00e9decine (1994) , Cusco, P\u00e9rou. &lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/03-Jorge-DSC_1708-recadre-BD.jpg?fit=584%2C221&amp;ssl=1\" class=\"size-full wp-image-5122\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/03-Jorge-DSC_1708-recadre-BD.jpg?resize=584%2C221&#038;ssl=1\" alt=\"\" width=\"584\" height=\"221\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/03-Jorge-DSC_1708-recadre-BD.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/03-Jorge-DSC_1708-recadre-BD.jpg?resize=300%2C114&amp;ssl=1 300w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/03-Jorge-DSC_1708-recadre-BD.jpg?resize=768%2C291&amp;ssl=1 768w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/03-Jorge-DSC_1708-recadre-BD.jpg?resize=500%2C189&amp;ssl=1 500w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a><p id=\"caption-attachment-5122\" class=\"wp-caption-text\">(ill.\u00a04) Jorge Luis Chirinos V\u00e1squez, <em><strong>P<\/strong><strong><em>a<\/em>sado, presente y futuro de la Medicina<\/strong><\/em>\u00a0Pass\u00e9, pr\u00e9sent et futur de la M\u00e9decine (1994), Cusco, P\u00e9rou.<\/p><\/div>\n<p>\u00c0 l\u2019\u00e9poque o\u00f9 l\u2019Empire Inca<a href=\"#_ftn3\" name=\"_ftnref3\">[3]<\/a> s\u2019\u00e9tendait au-del\u00e0 du P\u00e9rou, l\u2019ex\u00e9cution du dernier empereur Atahualpa a marqu\u00e9 la disparition d\u2019un empire mais pas de la civilisation inca qui a perdur\u00e9 sous diff\u00e9rentes formes depuis.<\/p>\n<p>\u00c0 partir de l\u00e0, d\u00e8s le XVI<sup>e<\/sup> si\u00e8cle, le syst\u00e8me administratif colonial de la Vice-Royaut\u00e9 du P\u00e9rou s\u00e9pare en deux groupes l\u2019ensemble de la population. D\u2019une part, une \u201c\u00a0R\u00e9publique des Espagnols\u00a0\u201d, et, d\u2019autre part, une \u201c\u00a0R\u00e9publique des Indiens\u00a0\u201d. Cette s\u00e9paration sociale et culturelle a eu pour effet de fortifier un sentiment d\u2019appartenance identitaire et a \u00e9t\u00e9 utilis\u00e9e pour strat\u00e9giquement pr\u00e9server l\u2019identit\u00e9 inca\u00efque. La lign\u00e9e nobiliaire descendant des Incas a fait perdurer cet h\u00e9ritage culturel \u2014 partag\u00e9 par la population autochtone et consid\u00e9r\u00e9 par la communaut\u00e9 espagnole coloniale \u2014 en le rendant visible par des signes, des symboles, des costumes et lors de c\u00e9r\u00e9monies et de repr\u00e9sentations publiques. Dans cette continuit\u00e9, le nationalisme inca qui s\u2019est d\u00e9velopp\u00e9 au cours du XVIII<sup>e<\/sup> si\u00e8cle, a v\u00e9hicul\u00e9 une id\u00e9ologie pr\u00f4nant l\u2019identit\u00e9 andine des origines \u00e0 une l\u2019\u00e9poque o\u00f9 l\u2019Espagne a cherch\u00e9 \u00e0 obtenir de plus grands profits de sa colonie en mettant en place un syst\u00e8me administratif oppressant qui a g\u00e9n\u00e9r\u00e9 de nombreux soul\u00e8vements.<\/p>\n<p>La r\u00e9volte la plus importante de cette p\u00e9riode a \u00e9t\u00e9 men\u00e9e par Jos\u00e9 Gabriel Condorcanqui<a href=\"#_ftn4\" name=\"_ftnref4\">[4]<\/a> (1738-1781), administrateur qui a incarn\u00e9 le mouvement anticolonial de mani\u00e8re embl\u00e9matique. Il sera finalement captur\u00e9 et ex\u00e9cut\u00e9 par les Espagnols, ces derniers prendront par la suite des mesures r\u00e9pressives contre la culture indig\u00e8ne. Elles se traduiront par plusieurs interdictions<a href=\"#_ftn5\" name=\"_ftnref5\">[5]<\/a>\u00a0: d\u00e8s lors, la culture inca\u00efque devient subversive.<\/p>\n<p>Cons\u00e9quemment, se d\u00e9veloppent dans les pratiques plastiques une dissimulation des repr\u00e9sentations et des symboles \u00e9manant de la culture inca, en particulier au travers de la peinture murale du sud-andin qui compte de nombreuses \u0153uvres et dont la plupart sont r\u00e9alis\u00e9es par des peintres rest\u00e9s anonymes.<\/p>\n<p><span style=\"color: #800000;\"><strong>Le muraliste p\u00e9ruvien\u00a0: Tadeo Escalante (ca 1770-1840)<\/strong><\/span><\/p>\n<p>Parmi les rares peintres muralistes du Sud-andin qui ont put \u00eatre identifi\u00e9s, Tadeo Escalante s\u2019av\u00e8re un personnage singulier. Ce cr\u00e9ateur n\u00e9 au cours des derni\u00e8res d\u00e9cennies du XVIII<sup>e<\/sup> si\u00e8cle s\u2019inscrit dans la p\u00e9riode de transition entre l\u2019\u00e9poque coloniale et l\u2019av\u00e8nement de la R\u00e9publique du P\u00e9rou. Il est originaire d\u2019une ville situ\u00e9e \u00e0 140 km \u00e0 l\u2019est de Cusco, la cit\u00e9 d\u2019Acomayo<a href=\"#_ftn6\" name=\"_ftnref6\">[6]<\/a>, o\u00f9 vivent encore aujourd\u2019hui les descendants de sa famille. L\u2019un deux, Nicol\u00e1s Escalante (ill. 5), l\u2019arri\u00e8re-arri\u00e8re petit neveu du peintre, a h\u00e9rit\u00e9 du Moulin des Incas, un des deux moulins qui appartenait \u00e0 son anc\u00eatre (ill. 6). Il ne sera pas trait\u00e9 ici du deuxi\u00e8me moulin, le Moulin de la Gen\u00e8se. C&rsquo;est le Moulin des Incas \u0153uvre de Tadeo Escalante qui va faire l&rsquo;objet d&rsquo;une analyse d\u00e9taill\u00e9e : cette peinture murale a pour sc\u00e8ne principale une repr\u00e9sentation des \u00ab\u00a0Quatorze Incas\u00a0\u00bb.<\/p>\n<div class=\"tiled-gallery type-rectangular tiled-gallery-unresized\" data-original-width=\"584\" data-carousel-extra='{&quot;blog_id&quot;:1,&quot;permalink&quot;:&quot;https:\\\/\\\/alaincardenas.com\\\/blog\\\/portraits-dhier-et-de-demain-3-de-la-peinture-murale-peruvienne-a-propos-de-deux-oeuvres-tadeo-escalante-muraliste-du-sud-andin-1\\\/&quot;,&quot;likes_blog_id&quot;:129720831}' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 584px; height: 280px;\" data-original-width=\"584\" data-original-height=\"280\" > <div class=\"gallery-group images-1\" style=\"width: 211px; height: 280px;\" data-original-width=\"211\" data-original-height=\"280\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/alaincardenas.com\/blog\/portraits-dhier-et-de-demain-3-de-la-peinture-murale-peruvienne-a-propos-de-deux-oeuvres-tadeo-escalante-muraliste-du-sud-andin-1\/05-dsc_4090\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"207\"> <meta itemprop=\"height\" content=\"276\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"5124\" data-orig-file=\"https:\/\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/05-DSC_4090.jpg\" data-orig-size=\"450,600\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;F3311&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1570979035&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.5&quot;,&quot;iso&quot;:&quot;156&quot;,&quot;shutter_speed&quot;:&quot;0.0083309997199664&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/05-DSC_4090.jpg?fit=225%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/05-DSC_4090.jpg?fit=450%2C600&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/05-DSC_4090.jpg?w=207&#038;h=276&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/05-DSC_4090.jpg?w=450&amp;ssl=1 450w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/05-DSC_4090.jpg?resize=225%2C300&amp;ssl=1 225w\" width=\"207\" height=\"276\" loading=\"lazy\" data-original-width=\"207\" data-original-height=\"276\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"(ill. 5)\" style=\"width: 207px; height: 276px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> (ill. 5) <\/div> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 373px; height: 280px;\" data-original-width=\"373\" data-original-height=\"280\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/alaincardenas.com\/blog\/portraits-dhier-et-de-demain-3-de-la-peinture-murale-peruvienne-a-propos-de-deux-oeuvres-tadeo-escalante-muraliste-du-sud-andin-1\/06-dsc_4125-bd\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"369\"> <meta itemprop=\"height\" content=\"276\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"5125\" data-orig-file=\"https:\/\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/06-DSC_4125-BD.jpg\" data-orig-size=\"600,450\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;F3311&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1570980285&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.5&quot;,&quot;iso&quot;:&quot;118&quot;,&quot;shutter_speed&quot;:&quot;0.0082809998768625&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/06-DSC_4125-BD.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/06-DSC_4125-BD.jpg?fit=584%2C438&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/06-DSC_4125-BD.jpg?w=369&#038;h=276&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/06-DSC_4125-BD.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/06-DSC_4125-BD.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/06-DSC_4125-BD.jpg?resize=400%2C300&amp;ssl=1 400w\" width=\"369\" height=\"276\" loading=\"lazy\" data-original-width=\"369\" data-original-height=\"276\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"(ill. 6)\" style=\"width: 369px; height: 276px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> (ill. 6) <\/div> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <\/div>\n<hr \/>\n<p>Ci-dessus (ill. 5) Nicol\u00e1s Escalante devant le Moulin des Incas. (ill. 6) Vue g\u00e9n\u00e9rale du Moulin des Incas [mission de recherche Alain Cardenas-Castro, r\u00e9gion de Cuzco, octobre 2019].<\/p>\n<hr \/>\n<p>Il n\u2019existe aucun t\u00e9moignage d\u2019un \u00e9ventuel apprentissage de Tadeo Escalante \u00e0 la peinture ni \u00e0 ses techniques dans l\u2019un des nombreux ateliers qui existaient alors \u00e0 Cusco. D\u2019ailleurs, le peu que l\u2019on conna\u00eet de la vie du peintre se r\u00e9sume \u00e0 des hypoth\u00e8ses et la plupart sont issues des d\u00e9ductions faites \u00e0 partir de ses \u0153uvres. Tadeo Escalante, autodidacte f\u00e9cond, travaille sans faire appel aux r\u00e8gles strictes de la perspective ni \u00e0 une pratique approximative des techniques du dessin et de la peinture. Pour l\u2019historien de l\u2019art Pablo Macera<a href=\"#_ftn7\" name=\"_ftnref7\">[7]<\/a>, ses manques et ses faiblesses seraient d\u00e9lib\u00e9r\u00e9s\u00a0: son style baroque m\u00e9tiss\u00e9 servirait \u00e0 d\u00e9montrer l&rsquo;ind\u00e9pendance de l&rsquo;art de Cuzco des influences \u00e9trang\u00e8res, en ignorant l&rsquo;acad\u00e9misme dominant et tendant vers un art populaire, g\u00e9n\u00e9rant les bases de la production de l&rsquo;\u00e9cole des \u00ab\u00a0primitifs andins\u00a0\u00bb, ces peintres populaires qui ont d\u00e9velopp\u00e9 leur activit\u00e9 \u00e0 Cusco pendant une grande partie du XIX<sup>e<\/sup> si\u00e8cle.<\/p>\n<p>Effectivement, quand on observe attentivement les repr\u00e9sentations des Incas qu\u2019il a r\u00e9alis\u00e9es sur les murs de cet ancien moulin \u00e0 bl\u00e9, on arrive \u00e0 percevoir le savoir d\u2019un peintre \u00e9rudit. Tadeo Escalante a certainement lu les <em>Comentarios reales<\/em><a href=\"#_ftn8\" name=\"_ftnref8\">[8]<\/a> de l&rsquo;Inca Garcilaso de la Vega et \u00e9galement pris des r\u00e9f\u00e9rences iconographiques dans les <em>D\u00e9cadas de Indias <\/em><a href=\"#_ftn9\" name=\"_ftnref9\">[9]<\/a> o\u00f9 l\u2019on peut voir des repr\u00e9sentations d\u2019Incas. Il puise ainsi parmi ces r\u00e9f\u00e9rences pour peindre sa s\u00e9rie d\u2019Incas et de <em>qoyas<\/em><a href=\"#_ftn10\" name=\"_ftnref10\">[10]<\/a>.<\/p>\n<p><span style=\"color: #800000;\"><strong>\u00a0<\/strong><strong>Les peintures murales du Moulin des Incas situ\u00e9 \u00e0 Acomayo<\/strong><\/span><\/p>\n<p>\u00c0 Acomayo, j&rsquo;ai \u00e9t\u00e9 re\u00e7u par Nicol\u00e1s Escalante qui nous a permis de p\u00e9n\u00e9trer dans le Moulin des Incas afin de voir les peintures murales et d\u2019en r\u00e9aliser quelques clich\u00e9s photographiques.<\/p>\n<p>Comme le rappelle ce descendant de peintre, \u00ab\u00a0le moulin est rest\u00e9 dans un \u00e9tat qui devrait permettre de lui restituer ais\u00e9ment sa fonction premi\u00e8re. Cependant, je tiens \u00e0 souligner que l\u2019enveloppe du b\u00e2timent a souffert de la faiblesse de sa toiture, celle-ci a \u00e9t\u00e9 endommag\u00e9e par les intemp\u00e9ries et a subi des infiltrations dommageables. Cependant, le gouvernement a financ\u00e9 la pose d\u2019une protection en plastique de mani\u00e8re provisoire pour mettre fin aux d\u00e9g\u00e2ts caus\u00e9s par l\u2019eau dans la toiture de l\u2019\u00e9difice. Cette mesure a \u00e9t\u00e9 prise dans l\u2019attente de mesures de conservation compl\u00e9mentaires visant \u00e0 \u00e9viter de futures d\u00e9gradations<a href=\"#_ftn11\" name=\"_ftnref11\">[11]<\/a>\u00a0\u00bb.<\/p>\n<p>Avant de p\u00e9n\u00e9trer \u00e0 l\u2019int\u00e9rieur du b\u00e2timent on remarque plusieurs repr\u00e9sentations qui ornent les murs du porche. Au centre, sur le mur fronton, un Saint Christophe (ill. 7) surplombe la porte d\u2019entr\u00e9e. Sur le mur de droite, une repr\u00e9sentation de Saint Martin de Tours (ill. 8) c\u00f4toie une repr\u00e9sentation d&rsquo;une <em>bouche de l\u2019Enfer<\/em>, et sur le mur de gauche de la porte d\u2019entr\u00e9e, une repr\u00e9sentation de Santiago Matamoros<a href=\"#_ftn12\" name=\"_ftnref12\">[12]<\/a> (ill. 9). Des manques importants auxquels s\u2019ajoute un mauvais \u00e9tat de conservation, perturbent la lecture des peintures repr\u00e9sentant les deux cavaliers plac\u00e9s de part et d\u2019autre du Saint Christophe. Ces repr\u00e9sentations religieuses qui accueillent d\u00e8s la fa\u00e7ade ext\u00e9rieure du b\u00e2timent permettent de d\u00e9tourner l\u2019attention du visiteur et de pr\u00e9server l\u2019intensit\u00e9 des images profanes et subversives cach\u00e9es \u00e0 l\u2019int\u00e9rieur du Moulin.<\/p>\n<div class=\"tiled-gallery type-rectangular tiled-gallery-unresized\" data-original-width=\"584\" data-carousel-extra='{&quot;blog_id&quot;:1,&quot;permalink&quot;:&quot;https:\\\/\\\/alaincardenas.com\\\/blog\\\/portraits-dhier-et-de-demain-3-de-la-peinture-murale-peruvienne-a-propos-de-deux-oeuvres-tadeo-escalante-muraliste-du-sud-andin-1\\\/&quot;,&quot;likes_blog_id&quot;:129720831}' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 584px; height: 220px;\" data-original-width=\"584\" data-original-height=\"220\" > <div class=\"gallery-group images-1\" style=\"width: 292px; height: 220px;\" data-original-width=\"292\" data-original-height=\"220\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/alaincardenas.com\/blog\/portraits-dhier-et-de-demain-3-de-la-peinture-murale-peruvienne-a-propos-de-deux-oeuvres-tadeo-escalante-muraliste-du-sud-andin-1\/07-dsc_4092-bd\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"288\"> <meta itemprop=\"height\" content=\"216\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"5126\" data-orig-file=\"https:\/\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/07-DSC_4092-BD.jpg\" data-orig-size=\"600,450\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;F3311&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1570979044&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.5&quot;,&quot;iso&quot;:&quot;207&quot;,&quot;shutter_speed&quot;:&quot;0.0083309997199664&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/07-DSC_4092-BD.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/07-DSC_4092-BD.jpg?fit=584%2C438&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/07-DSC_4092-BD.jpg?w=288&#038;h=216&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/07-DSC_4092-BD.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/07-DSC_4092-BD.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/07-DSC_4092-BD.jpg?resize=400%2C300&amp;ssl=1 400w\" width=\"288\" height=\"216\" loading=\"lazy\" data-original-width=\"288\" data-original-height=\"216\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"(ill. 7)\" style=\"width: 288px; height: 216px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> (ill. 7) <\/div> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 292px; height: 220px;\" data-original-width=\"292\" data-original-height=\"220\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/alaincardenas.com\/blog\/portraits-dhier-et-de-demain-3-de-la-peinture-murale-peruvienne-a-propos-de-deux-oeuvres-tadeo-escalante-muraliste-du-sud-andin-1\/08-dsc_4084-bd\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"288\"> <meta itemprop=\"height\" content=\"216\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"5127\" data-orig-file=\"https:\/\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/08-DSC_4084-BD.jpg\" data-orig-size=\"600,450\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;F3311&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1570978948&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.5&quot;,&quot;iso&quot;:&quot;180&quot;,&quot;shutter_speed&quot;:&quot;0.0083309997199664&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/08-DSC_4084-BD.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/08-DSC_4084-BD.jpg?fit=584%2C438&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/08-DSC_4084-BD.jpg?w=288&#038;h=216&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/08-DSC_4084-BD.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/08-DSC_4084-BD.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/08-DSC_4084-BD.jpg?resize=400%2C300&amp;ssl=1 400w\" width=\"288\" height=\"216\" loading=\"lazy\" data-original-width=\"288\" data-original-height=\"216\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"(ill. 8)\" style=\"width: 288px; height: 216px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> (ill. 8) <\/div> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <\/div>\n<hr \/>\n<p>Ci-dessus, de gauche \u00e0 droite. (ill.\u00a07) Tadeo Escalante, Saint Christophe, Moulin des Incas, Acomayo, P\u00e9rou.\u00a0(ill.\u00a08) Tadeo Escalante, Saint Martin de Tours et <em>la bouche de l\u2019Enfer<\/em>, Moulin des Incas, Acomayo, P\u00e9rou<\/p>\n<hr \/>\n<div id=\"attachment_5128\" style=\"width: 397px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/09-IMG_20191013_151842.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5128\" data-attachment-id=\"5128\" data-permalink=\"https:\/\/alaincardenas.com\/blog\/portraits-dhier-et-de-demain-3-de-la-peinture-murale-peruvienne-a-propos-de-deux-oeuvres-tadeo-escalante-muraliste-du-sud-andin-1\/09-img_20191013_151842\/\" data-orig-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/09-IMG_20191013_151842.jpg?fit=450%2C600&amp;ssl=1\" data-orig-size=\"450,600\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;DRA-LX3&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1570979923&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.5&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.0085040004025562&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"09 IMG_20191013_151842\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/09-IMG_20191013_151842.jpg?fit=450%2C600&amp;ssl=1\" class=\"wp-image-5128 \" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/09-IMG_20191013_151842.jpg?resize=387%2C512&#038;ssl=1\" alt=\"\" width=\"387\" height=\"512\" \/><\/a><p id=\"caption-attachment-5128\" class=\"wp-caption-text\">(ill.\u00a09) Tadeo Escalante, Santiago Matamoros repr\u00e9sent\u00e9 sous le porche d&rsquo;entr\u00e9e du Moulin des Incas, Acomayo, P\u00e9rou<\/p><\/div>\n<p>Mais, ces images introductives, bien que tir\u00e9es de l\u2019iconographie religieuse traditionnelle, peuvent aussi se lire diff\u00e9remment, par exemple, au travers d\u2019une lecture \u00e0 double sens de quelques-uns des motifs trait\u00e9s par Tadeo Escalante de mani\u00e8re plus qu\u2019insolite. Ainsi, les deux cavaliers, de part et d\u2019autre de l\u2019entr\u00e9e du moulin d\u00e9livrent un message ambivalent entre le bien et le mal\u00a0: le charitable Saint Martin partage sa cape avec un n\u00e9cessiteux alors que la figure de Saint Jacques peut se lire comme la figure du <em>Mataindio<\/em>s<a href=\"#_ftn13\" name=\"_ftnref13\">[13]<\/a>. Entre ces deux figures, Saint Christophe accueille \u00e0 l\u2019entr\u00e9e de l\u2019\u00e9difice en portant le Christ, comme cela est habituel dans l\u2019iconographie, mais, son bras gauche traverse en son centre un bouclier, et son \u00e9paule droite supporte un Enfant J\u00e9sus par\u00e9 d\u2019une cape comme form\u00e9e de plumes. Ces repr\u00e9sentations singuli\u00e8res rappellent les manifestations identitaires inca\u00efques diffus\u00e9es \u00e0 cette \u00e9poque de mani\u00e8re dissimul\u00e9e. Tadeo Escalante applique pr\u00e9cautionneusement ces types de repr\u00e9sentations \u00e0 l\u2019entr\u00e9e de son moulin. Cette \u0153uvre est certainement n\u00e9e aussi parce qu\u2019il a \u00e9t\u00e9 sensibilis\u00e9 \u00e0 la cause rebelle et revendicatrice du spectacle de l\u2019ex\u00e9cution des martyres de la \u00ab\u00a0Grande R\u00e9bellion<a href=\"#_ftn14\" name=\"_ftnref14\">[14]<\/a>\u00bb de 1780, spectacle auquel il a assist\u00e9 \u00e0 Cuzco quand il \u00e9tait enfant.<\/p>\n<p><span style=\"color: #800000;\"><strong>Des peintures murales dans un moulin \u00e0 bl\u00e9<\/strong><\/span><\/p>\n<div id=\"attachment_5129\" style=\"width: 199px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/10-Capture-d%E2%80%99%C3%A9cran-2020-06-11-%C3%A0-13.59.45.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5129\" data-attachment-id=\"5129\" data-permalink=\"https:\/\/alaincardenas.com\/blog\/portraits-dhier-et-de-demain-3-de-la-peinture-murale-peruvienne-a-propos-de-deux-oeuvres-tadeo-escalante-muraliste-du-sud-andin-1\/10-capture-decran-2020-06-11-a-13-59-45\/\" data-orig-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/10-Capture-d%E2%80%99%C3%A9cran-2020-06-11-%C3%A0-13.59.45.jpg?fit=235%2C359&amp;ssl=1\" data-orig-size=\"235,359\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"10 Capture d\u2019\u00e9cran 2020-06-11 \u00e0 13.59.45\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/10-Capture-d%E2%80%99%C3%A9cran-2020-06-11-%C3%A0-13.59.45.jpg?fit=235%2C359&amp;ssl=1\" class=\"wp-image-5129 \" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/10-Capture-d%E2%80%99%C3%A9cran-2020-06-11-%C3%A0-13.59.45.jpg?resize=189%2C285&#038;ssl=1\" alt=\"\" width=\"189\" height=\"285\" \/><\/a><p id=\"caption-attachment-5129\" class=\"wp-caption-text\">(ill. 10) Capaq Yupanqui, the cinqui\u00e8me inca, Martin de Murua Historia general del Piru, 1616, Ms. Ludwig XIII 16 (83.MP.159), fol 30V; J. Paul Getty Museum.<\/p><\/div>\n<p>La th\u00e9matique profane des Incas n\u2019est pas rare au XVIII<sup>e<\/sup> s. Elle est, d\u2019une part, en lien avec le nationalisme inca de l\u2019\u00e9poque, et, d\u2019autre part, d\u00e9j\u00e0, en 1571, Francisco de Toledo, envoie \u00e0 la Couronne des sc\u00e8nes peintes sur toile de la vie de l\u2019Ancien P\u00e9rou avec des repr\u00e9sentations d\u2019Incas<a href=\"#_ftn15\" name=\"_ftnref15\">[15]<\/a> figur\u00e9s \u00e9galement par le dessin et l\u2018aquarelle sur un des manuscrits r\u00e9dig\u00e9 en 1613 par Martin de Mur\u00faa<a href=\"#_ftn16\" name=\"_ftnref16\">[16]<\/a> (ill. 10).<\/p>\n<p>Ce lieu est baign\u00e9 dans une p\u00e9nombre \u00e9clair\u00e9 par deux sources de lumi\u00e8re, celle de la porte d&rsquo;entr\u00e9e et celle d&rsquo;une autre porte lat\u00e9rale, toutes deux laiss\u00e9es ouvertes pour cette visite. La configuration de l\u2019espace, \u00e9tonnante, rappelle la nef d\u2019une \u00e9glise (ill. 11). Cette impression est renforc\u00e9e par la peinture murale du fond,\u00a0bas\u00e9e sur une composition sym\u00e9trique\u00a0repr\u00e9sentant un autel encadr\u00e9 de part et d\u2019autre par les motifs similaires de deux personnages munis d\u2019\u00e9chelles et de deux arbres de taille moyenne (ill. 12). Ces repr\u00e9sentations religieuses viennent contraster avec les repr\u00e9sentations profanes des murs lat\u00e9raux.<\/p>\n<div id=\"attachment_5130\" style=\"width: 461px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/11-DSC_4097-BD.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5130\" data-attachment-id=\"5130\" data-permalink=\"https:\/\/alaincardenas.com\/blog\/portraits-dhier-et-de-demain-3-de-la-peinture-murale-peruvienne-a-propos-de-deux-oeuvres-tadeo-escalante-muraliste-du-sud-andin-1\/11-dsc_4097-bd\/\" data-orig-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/11-DSC_4097-BD.jpg?fit=600%2C450&amp;ssl=1\" data-orig-size=\"600,450\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;F3311&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1570979115&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.5&quot;,&quot;iso&quot;:&quot;2993&quot;,&quot;shutter_speed&quot;:&quot;0.04999500049995&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"11 DSC_4097 BD\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/11-DSC_4097-BD.jpg?fit=584%2C438&amp;ssl=1\" class=\"wp-image-5130 \" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/11-DSC_4097-BD.jpg?resize=451%2C341&#038;ssl=1\" alt=\"\" width=\"451\" height=\"341\" \/><\/a><p id=\"caption-attachment-5130\" class=\"wp-caption-text\">(ill. 11) L\u2019int\u00e9rieur du Moulin des Incas<\/p><\/div>\n\n\t\t<style>\n\t\t\t#gallery-3 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-3 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-3 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-3 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div data-carousel-extra='{&quot;blog_id&quot;:1,&quot;permalink&quot;:&quot;https:\/\/alaincardenas.com\/blog\/portraits-dhier-et-de-demain-3-de-la-peinture-murale-peruvienne-a-propos-de-deux-oeuvres-tadeo-escalante-muraliste-du-sud-andin-1\/&quot;}' id='gallery-3' class='gallery galleryid-5118 gallery-columns-2 gallery-size-large'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/alaincardenas.com\/blog\/portraits-dhier-et-de-demain-3-de-la-peinture-murale-peruvienne-a-propos-de-deux-oeuvres-tadeo-escalante-muraliste-du-sud-andin-1\/12-dsc_4071\/'><img loading=\"lazy\" decoding=\"async\" width=\"443\" height=\"482\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/12-DSC_4071.jpg?fit=443%2C482&amp;ssl=1\" class=\"attachment-large size-large\" alt=\"\" aria-describedby=\"gallery-3-5131\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/12-DSC_4071.jpg?w=443&amp;ssl=1 443w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/12-DSC_4071.jpg?resize=276%2C300&amp;ssl=1 276w\" sizes=\"auto, (max-width: 443px) 100vw, 443px\" data-attachment-id=\"5131\" data-permalink=\"https:\/\/alaincardenas.com\/blog\/portraits-dhier-et-de-demain-3-de-la-peinture-murale-peruvienne-a-propos-de-deux-oeuvres-tadeo-escalante-muraliste-du-sud-andin-1\/12-dsc_4071\/\" data-orig-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/12-DSC_4071.jpg?fit=443%2C482&amp;ssl=1\" data-orig-size=\"443,482\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;F3311&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1570978216&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.5&quot;,&quot;iso&quot;:&quot;3141&quot;,&quot;shutter_speed&quot;:&quot;0.04999500049995&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;(ill. 12) L\u2019autel repr\u00e9sent\u00e9 sur le mur du fond du Moulin des Incas &lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/12-DSC_4071.jpg?fit=443%2C482&amp;ssl=1\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-3-5131'>\n\t\t\t\t(ill. 12) L\u2019autel repr\u00e9sent\u00e9 sur le mur du fond du Moulin des Incas \n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/alaincardenas.com\/blog\/portraits-dhier-et-de-demain-3-de-la-peinture-murale-peruvienne-a-propos-de-deux-oeuvres-tadeo-escalante-muraliste-du-sud-andin-1\/13-dsc_4073-bd\/'><img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"438\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/13-DSC_4073-BD.jpg?fit=584%2C438&amp;ssl=1\" class=\"attachment-large size-large\" alt=\"\" aria-describedby=\"gallery-3-5132\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/13-DSC_4073-BD.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/13-DSC_4073-BD.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/13-DSC_4073-BD.jpg?resize=400%2C300&amp;ssl=1 400w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" data-attachment-id=\"5132\" data-permalink=\"https:\/\/alaincardenas.com\/blog\/portraits-dhier-et-de-demain-3-de-la-peinture-murale-peruvienne-a-propos-de-deux-oeuvres-tadeo-escalante-muraliste-du-sud-andin-1\/13-dsc_4073-bd\/\" data-orig-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/13-DSC_4073-BD.jpg?fit=600%2C450&amp;ssl=1\" data-orig-size=\"600,450\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;F3311&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1570978241&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.5&quot;,&quot;iso&quot;:&quot;3141&quot;,&quot;shutter_speed&quot;:&quot;0.04999500049995&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;(ill. 13) Une partie de la s\u00e9rie des Incas sur le mur de droite du Moulin des Incas&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/13-DSC_4073-BD.jpg?fit=584%2C438&amp;ssl=1\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-3-5132'>\n\t\t\t\t(ill. 13) Une partie de la s\u00e9rie des Incas sur le mur de droite du Moulin des Incas\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p>Sur le mur de droite, la s\u00e9rie des Incas (ill. 13) commence avec les peintures de deux premiers Incas suivis d\u2019une vigogne et de deux des \u00e9pouses du premier Inca, Mama Huaco et Mama Occllo, accompagn\u00e9es de bossus (<em>k\u2019umillu<\/em>) soutenant des parasols imp\u00e9riaux (<em>achiwa<\/em>) au-dessus de la t\u00eate des deux \u00e9pouses (ill. 14). On retrouve l\u2019influence des peintures et dessins de Felipe Guaman Poma de Ayala et du fr\u00e8re Martin de Mur\u00faa et aussi celle des sc\u00e8nes peintes sur les importants vases c\u00e9r\u00e9moniels, le plus souvent en bois, les <em>keros<\/em><a href=\"#_ftn17\" name=\"_ftnref17\">[17]<\/a>, sur lesquels les Incas sont d\u00e9crits suivant le registre iconographique utilis\u00e9 \u00e0 l\u2019\u00e9poque. Tadeo Escalante repr\u00e9sente ici, les Incas de face, avec tous leurs attributs royaux. De plus, ces personnages sont trait\u00e9s plus librement comme l\u2019indiquent leurs tuniques caract\u00e9ristiques (<em>unku<\/em>), orn\u00e9es de <em>tokapus<\/em> dont les motifs sont des fleurs de lys, ainsi que les sceptres qu\u2019ils tiennent en main, des haches. Les coiffes aussi sont diff\u00e9rentes et les repr\u00e9sentations du soleil \u00e0 visages humains qu\u2019ils arborent, s\u2019inspirent des repr\u00e9sentations id\u00e9alis\u00e9es des monarques europ\u00e9ens. Les <em>qoyas<\/em> qui les accompagnent filent de la laine de vigogne et portent des sandales rappelant celles qu\u2019utilisent les bergers des hauts plateaux andins.<\/p>\n\n\t\t<style>\n\t\t\t#gallery-4 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-4 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-4 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-4 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div data-carousel-extra='{&quot;blog_id&quot;:1,&quot;permalink&quot;:&quot;https:\/\/alaincardenas.com\/blog\/portraits-dhier-et-de-demain-3-de-la-peinture-murale-peruvienne-a-propos-de-deux-oeuvres-tadeo-escalante-muraliste-du-sud-andin-1\/&quot;}' id='gallery-4' class='gallery galleryid-5118 gallery-columns-2 gallery-size-large'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/alaincardenas.com\/blog\/portraits-dhier-et-de-demain-3-de-la-peinture-murale-peruvienne-a-propos-de-deux-oeuvres-tadeo-escalante-muraliste-du-sud-andin-1\/14-dsc_4120-bd\/'><img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"438\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/14-DSC_4120-bd.jpg?fit=584%2C438&amp;ssl=1\" class=\"attachment-large size-large\" alt=\"\" aria-describedby=\"gallery-4-5133\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/14-DSC_4120-bd.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/14-DSC_4120-bd.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/14-DSC_4120-bd.jpg?resize=400%2C300&amp;ssl=1 400w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" data-attachment-id=\"5133\" data-permalink=\"https:\/\/alaincardenas.com\/blog\/portraits-dhier-et-de-demain-3-de-la-peinture-murale-peruvienne-a-propos-de-deux-oeuvres-tadeo-escalante-muraliste-du-sud-andin-1\/14-dsc_4120-bd\/\" data-orig-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/14-DSC_4120-bd.jpg?fit=600%2C450&amp;ssl=1\" data-orig-size=\"600,450\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;F3311&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1570979542&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.5&quot;,&quot;iso&quot;:&quot;3141&quot;,&quot;shutter_speed&quot;:&quot;0.04999500049995&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;(ill.\u00a014) Deux \u00e9pouses du premier Inca repr\u00e9sent\u00e9es sur le mur lat\u00e9ral droit du Moulin des Incas&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/14-DSC_4120-bd.jpg?fit=584%2C438&amp;ssl=1\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-4-5133'>\n\t\t\t\t(ill.\u00a014) Deux \u00e9pouses du premier Inca repr\u00e9sent\u00e9es sur le mur lat\u00e9ral droit du Moulin des Incas\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/alaincardenas.com\/blog\/portraits-dhier-et-de-demain-3-de-la-peinture-murale-peruvienne-a-propos-de-deux-oeuvres-tadeo-escalante-muraliste-du-sud-andin-1\/15-dsc_4117-bd\/'><img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"438\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/15-DSC_4117-bd.jpg?fit=584%2C438&amp;ssl=1\" class=\"attachment-large size-large\" alt=\"\" aria-describedby=\"gallery-4-5134\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/15-DSC_4117-bd.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/15-DSC_4117-bd.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/15-DSC_4117-bd.jpg?resize=400%2C300&amp;ssl=1 400w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" data-attachment-id=\"5134\" data-permalink=\"https:\/\/alaincardenas.com\/blog\/portraits-dhier-et-de-demain-3-de-la-peinture-murale-peruvienne-a-propos-de-deux-oeuvres-tadeo-escalante-muraliste-du-sud-andin-1\/15-dsc_4117-bd\/\" data-orig-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/15-DSC_4117-bd.jpg?fit=600%2C450&amp;ssl=1\" data-orig-size=\"600,450\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;F3311&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1570979502&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.5&quot;,&quot;iso&quot;:&quot;3141&quot;,&quot;shutter_speed&quot;:&quot;0.04999500049995&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;(ill.\u00a015) Le symbole du blason sur le mur lat\u00e9ral droit du Moulin des Incas&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/15-DSC_4117-bd.jpg?fit=584%2C438&amp;ssl=1\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-4-5134'>\n\t\t\t\t(ill.\u00a015) Le symbole du blason sur le mur lat\u00e9ral droit du Moulin des Incas\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<div id=\"attachment_5135\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/16-DSC_4067-BD.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5135\" data-attachment-id=\"5135\" data-permalink=\"https:\/\/alaincardenas.com\/blog\/portraits-dhier-et-de-demain-3-de-la-peinture-murale-peruvienne-a-propos-de-deux-oeuvres-tadeo-escalante-muraliste-du-sud-andin-1\/16-dsc_4067-bd\/\" data-orig-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/16-DSC_4067-BD.jpg?fit=600%2C450&amp;ssl=1\" data-orig-size=\"600,450\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;F3311&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1570978152&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.5&quot;,&quot;iso&quot;:&quot;3141&quot;,&quot;shutter_speed&quot;:&quot;0.04999500049995&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"16 DSC_4067 BD\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/16-DSC_4067-BD.jpg?fit=584%2C438&amp;ssl=1\" class=\"wp-image-5135 size-medium\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/16-DSC_4067-BD.jpg?resize=300%2C225&#038;ssl=1\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/16-DSC_4067-BD.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/16-DSC_4067-BD.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/16-DSC_4067-BD.jpg?w=600&amp;ssl=1 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-5135\" class=\"wp-caption-text\">(ill. 16) La tour\u00a0<em>Sunturhuasi<\/em> monument de l\u2019ancienne capitale des Incas est situ\u00e9e sur le mur lat\u00e9ral droit du Moulin des Incas<\/p><\/div>\n<p>Par ailleurs, parmi les symboles remarquables de la composition murale du Moulin des Incas, un blason (escudo) de grandes dimensions repr\u00e9sente plusieurs motifs se r\u00e9f\u00e9rant aux th\u00e8mes r\u00e9publicains, aux soci\u00e9t\u00e9s secr\u00e8tes ou aux loges patriotiques (ill. 15). La tour <em>Sunturhuasi,<\/em>\u00a0monument de l\u2019ancienne capitale des Incas est\u00a0aussi un embl\u00e8me important de la composition. Elle est plac\u00e9e entre les deux Incas Viracocha et Pachacuti (ill. 16). La tour <em>Sunturhuasi<\/em> \u00e9tait un espace rituel pour communiquer avec les d\u00e9funts et pour garder les troph\u00e9es des populations annex\u00e9es par les Incas.<\/p>\n<p>Plusieurs phylact\u00e8res parcourent la composition en mentionnant les noms des personnages et indiquant les liens qui les unissent et parfois leurs caract\u00e9ristiques.<\/p>\n<p><span style=\"color: #800000;\"><strong>La peinture murale de l\u2019\u00e9glise de Huaro<\/strong><\/span><\/p>\n<p>Les th\u00e8mes du Jugement dernier et de l\u2019Enfer remontent \u00e0 l\u2019\u00e9poque m\u00e9di\u00e9vale et apparaissent t\u00f4t en Am\u00e9rique latine. Le chroniqueur Guaman Poma de Ayala relate que \u00ab\u00a0Dans chaque \u00e9glise, il y aura un tableau du Jugement dernier o\u00f9 sera repr\u00e9sent\u00e9e la venue du Seigneur au Jugement, au ciel, sur la terre et les douleurs de l&rsquo;enfer\u00a0\u00bb.<\/p>\n<p>Cette th\u00e9matique de l\u2019Enfer a \u00e9t\u00e9 trait\u00e9e dans la peinture Sud-andine depuis la fin du XVI<sup>e <\/sup>si\u00e8cle, \u00e0 la <em>Capilla de Indios<\/em> \u00e0 c\u00f4t\u00e9 de l\u2019\u00e9glise de la Compa\u00f1\u00eda. Plusieurs autres repr\u00e9sentations ont \u00e9t\u00e9 ex\u00e9cut\u00e9es apr\u00e8s cette peinture murale aujourd\u2019hui disparue.<\/p>\n<p>Les peintures murales de l\u2019\u00e9glise San Juan Bautista de Huaro reprennent plusieurs th\u00e9matiques, dont celle de la fin des temps constitu\u00e9e de six peintures, des th\u00e8mes comme <em>El \u00c1rbol de la Vida <\/em>(l\u2019Arbre de vie), <em>las dos Muertes<\/em> (la Mort du Riche et la Mort du Pauvre), <em>la Muerte<\/em> (la Mort), <em>el Juicio Final<\/em> (le Jugement dernier), <em>Infierno<\/em> (de l\u2019Enfer) et <em>Gloria<\/em> (de la Gloire).<\/p>\n<p>Les peintures sont attribu\u00e9es \u00e0 Tadeo Escalante et ont \u00e9t\u00e9 ex\u00e9cut\u00e9es au d\u00e9but du XIX<sup>e<\/sup> si\u00e8cle, dans l\u2019\u00e9glise du petit village de Huaro, situ\u00e9 \u00e0 une quarantaine de kilom\u00e8tres, au sud-est de Cuzco. D\u00e9di\u00e9e \u00e0 Jean le Baptiste, l&rsquo;\u00e9glise a \u00e9t\u00e9 probablement construite \u00e0 la fin du XVII<sup>e<\/sup> s. Sa structure compos\u00e9e d\u2019une seule nef est de style classique. Sa fa\u00e7ade est agr\u00e9ment\u00e9e de d\u00e9corations indig\u00e8nes et flanqu\u00e9e d\u2019un clocher-mur. L\u2019\u00e9glise comporte un autel renaissance, sa face en argent a \u00e9t\u00e9 vol\u00e9e en 2008 et remplac\u00e9e depuis lors. L&rsquo;autel est parmi le plus ancien du P\u00e9rou. Une inscription indique la date de 1802 pour la r\u00e9alisation de ces peintures murales qui ont \u00e9t\u00e9 ex\u00e9cut\u00e9es \u00e0 la d\u00e9trempe, technique plus couramment utilis\u00e9e que la peinture \u00e0 fresque en Am\u00e9rique latine. Tadeo Escalante a employ\u00e9 pour cela des pigments naturels d\u2019origine v\u00e9g\u00e9tale et min\u00e9rale avec des liants comme la s\u00e8ve de <em>gigant\u00f3n<\/em> (<em>Armatocereus procerus<\/em> Rauh &amp; Backeberg).<\/p>\n<p>L\u2018ensemble des peintures se r\u00e9partit sur les surfaces sup\u00e9rieures des murs. La partie consacr\u00e9e \u00e0 l\u2019Enfer (ill. 17) est caract\u00e9ris\u00e9e par deux phylact\u00e8res se d\u00e9roulant \u00e0 deux endroits sur la longueur de la surface murale. Dans ce contexte tragique, \u00e9difiant, une suite de sc\u00e8nes de torture aux personnages confin\u00e9s dans des chaudrons par des d\u00e9mons dans l\u2019attente d\u2019\u00eatre d\u00e9vor\u00e9s par le L\u00e9viathan attire le regard des fid\u00e8les.<\/p>\n<div id=\"attachment_5136\" style=\"width: 428px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/17-Fresque_%C3%A9glise_huaro-BD.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5136\" data-attachment-id=\"5136\" data-permalink=\"https:\/\/alaincardenas.com\/blog\/portraits-dhier-et-de-demain-3-de-la-peinture-murale-peruvienne-a-propos-de-deux-oeuvres-tadeo-escalante-muraliste-du-sud-andin-1\/17-fresque_eglise_huaro-bd\/\" data-orig-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/17-Fresque_%C3%A9glise_huaro-BD.jpg?fit=600%2C400&amp;ssl=1\" data-orig-size=\"600,400\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;5.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 50D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1365588489&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;28&quot;,&quot;iso&quot;:&quot;3200&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"17 Fresque_\u00e9glise_huaro BD\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/17-Fresque_%C3%A9glise_huaro-BD.jpg?fit=584%2C389&amp;ssl=1\" class=\"wp-image-5136 \" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/17-Fresque_%C3%A9glise_huaro-BD.jpg?resize=418%2C281&#038;ssl=1\" alt=\"\" width=\"418\" height=\"281\" \/><\/a><p id=\"caption-attachment-5136\" class=\"wp-caption-text\">(ill. 17) La peinture murale de Tadeo Escalante repr\u00e9sentant l\u2019Enfer au-dessus de la porte donnant sur le Haut-ch\u0153ur \u00e0 l\u2019int\u00e9rieur de l\u2019\u00e9glise San Juan Bautista de Huaro<\/p><\/div>\n<p>Cette peinture murale de l\u2019Enfer, interpr\u00e9t\u00e9 par Tadeo Escalante a valu le commentaire particuli\u00e8rement engag\u00e9 de Jos\u00e9 Uriel Garc\u00eda<a href=\"#_ftn18\" name=\"_ftnref18\">[18]<\/a> (1894-1965), chercheur, partisan de l&rsquo;indig\u00e9nisme qui voit ici une repr\u00e9sentation par le peintre des <em>corregidores<\/em>, ces fonctionnaires du pouvoir colonial corrompus et abusifs qui ont malmen\u00e9 et pers\u00e9cut\u00e9 les indig\u00e8nes. Ce serait\u00a0une mani\u00e8re pour Tadeo Escalante de ch\u00e2tier les tortionnaires de Jos\u00e9 Gabriel Condorcanqui dit T\u00fapac Amaru II. Ce m\u00eame Jos\u00e9 Uriel Garc\u00eda\u00a0a consign\u00e9 cette tradition orale qui circulait dans le village de Huaro d\u2019apr\u00e8s don Victoriano Y\u00e1bar. Jos\u00e9 Uriel Garc\u00eda\u00a0a pu ainsi identifier trois personnages visibles sous le second phylact\u00e8re situ\u00e9\u00a0en partie basse de la composition. Le contenu du phylact\u00e8re peut \u00eatre traduit ainsi : \u00ab\u00a0Malheur \u00e0 moi qui br\u00fble. Malheur \u00e0 moi qui ne pouvais pas et ne peux plus. H\u00e9las, je dois br\u00fbler pour toujours. Malheur \u00e0 Dieu que je ne verrai jamais \u00bb. Trois \u00e9l\u00e9ments de cette composition sont d\u00e9crits ci-dessous :<\/p>\n<div class=\"tiled-gallery type-square tiled-gallery-unresized\" data-original-width=\"584\" data-carousel-extra='{&quot;blog_id&quot;:1,&quot;permalink&quot;:&quot;https:\\\/\\\/alaincardenas.com\\\/blog\\\/portraits-dhier-et-de-demain-3-de-la-peinture-murale-peruvienne-a-propos-de-deux-oeuvres-tadeo-escalante-muraliste-du-sud-andin-1\\\/&quot;,&quot;likes_blog_id&quot;:129720831}' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 584px; height: 194px;\" data-original-width=\"584\" data-original-height=\"194\" > <div class=\"gallery-group\" style=\"width: 194px; height: 194px;\" data-original-width=\"194\" data-original-height=\"194\" > <div class=\"tiled-gallery-item \" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/alaincardenas.com\/blog\/portraits-dhier-et-de-demain-3-de-la-peinture-murale-peruvienne-a-propos-de-deux-oeuvres-tadeo-escalante-muraliste-du-sud-andin-1\/areche-huaro\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"190\"> <meta itemprop=\"height\" content=\"190\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"5182\" data-orig-file=\"https:\/\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/Areche-Huaro.jpg\" data-orig-size=\"380,363\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Areche &amp;#8211; Huaro\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/Areche-Huaro.jpg?fit=300%2C287&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/Areche-Huaro.jpg?fit=380%2C363&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/Areche-Huaro.jpg?w=190&#038;h=190&#038;crop=1&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/Areche-Huaro.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/Areche-Huaro.jpg?zoom=2&amp;resize=190%2C190&amp;ssl=1 380w\" width=\"190\" height=\"190\" loading=\"lazy\" data-original-width=\"190\" data-original-height=\"190\" itemprop=\"http:\/\/schema.org\/image\" title=\"Areche - Huaro\" alt=\"(ill. 18)\" style=\"width: 190px; height: 190px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> (ill. 18) <\/div> <\/div> <\/div> <div class=\"gallery-group\" style=\"width: 194px; height: 194px;\" data-original-width=\"194\" data-original-height=\"194\" > <div class=\"tiled-gallery-item \" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/alaincardenas.com\/blog\/portraits-dhier-et-de-demain-3-de-la-peinture-murale-peruvienne-a-propos-de-deux-oeuvres-tadeo-escalante-muraliste-du-sud-andin-1\/matalinares-huaro\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"190\"> <meta itemprop=\"height\" content=\"190\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"5184\" data-orig-file=\"https:\/\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/Matalinares-Huaro.jpg\" data-orig-size=\"435,375\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Matalinares &amp;#8211; Huaro\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/Matalinares-Huaro.jpg?fit=300%2C259&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/Matalinares-Huaro.jpg?fit=435%2C375&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/Matalinares-Huaro.jpg?w=190&#038;h=190&#038;crop=1&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/Matalinares-Huaro.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/Matalinares-Huaro.jpg?zoom=2&amp;resize=190%2C190&amp;ssl=1 380w\" width=\"190\" height=\"190\" loading=\"lazy\" data-original-width=\"190\" data-original-height=\"190\" itemprop=\"http:\/\/schema.org\/image\" title=\"Matalinares - Huaro\" alt=\"(ill. 19)\" style=\"width: 190px; height: 190px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> (ill. 19) <\/div> <\/div> <\/div> <div class=\"gallery-group\" style=\"width: 194px; height: 194px;\" data-original-width=\"194\" data-original-height=\"194\" > <div class=\"tiled-gallery-item \" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/alaincardenas.com\/blog\/portraits-dhier-et-de-demain-3-de-la-peinture-murale-peruvienne-a-propos-de-deux-oeuvres-tadeo-escalante-muraliste-du-sud-andin-1\/del-valle-huaro\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"190\"> <meta itemprop=\"height\" content=\"190\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"5183\" data-orig-file=\"https:\/\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/Del-Valle-Huaro.jpg\" data-orig-size=\"313,384\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Del Valle &amp;#8211; Huaro\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/Del-Valle-Huaro.jpg?fit=245%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/Del-Valle-Huaro.jpg?fit=313%2C384&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/Del-Valle-Huaro.jpg?w=190&#038;h=190&#038;crop=1&#038;ssl=1\" width=\"190\" height=\"190\" loading=\"lazy\" data-original-width=\"190\" data-original-height=\"190\" itemprop=\"http:\/\/schema.org\/image\" title=\"Del Valle - Huaro\" alt=\"(ill. 20)\" style=\"width: 190px; height: 190px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> (ill. 20) <\/div> <\/div> <\/div> <\/div> <\/div>\n<hr \/>\n<p>Ci-dessus, de gauche \u00e0 droite. (ill. 18) Jos\u00e9 Antonio de Areche Zornoza,\u00a0(ill. 19) Benito de la Mata Linares, (ill. 20)\u00a0le mar\u00e9chal don Jos\u00e9 Del Valle.<\/p>\n<hr \/>\n<ul>\n<li>Le premier, Jos\u00e9 Antonio de Areche Zornoza\u00a0<a href=\"#_ftn19\" name=\"_ftnref19\">[19]<\/a>, devient un condamn\u00e9, allong\u00e9 sur une table situ\u00e9e en partie basse de la composition au dessus de la porte. Un d\u00e9mon se pr\u00e9pare a arracher la langue \u00e0 l\u2019aide d\u2019une pince. Areche \u00e9tait un haut fonctionnaire espagnol d\u2019origine basque de la vice-royaut\u00e9 du P\u00e9rou durant les ann\u00e9es de 1777 \u00e0 1787, il a pris part \u00e0 la mise en \u0153uvre des r\u00e9formes bourboniennes (ill. 18).<\/li>\n<\/ul>\n<ul>\n<li>Le deuxi\u00e8me, Benito de la Mata Linares, sous les traits d&rsquo;un condamn\u00e9, est peint devant la porte de l\u2019enfer situ\u00e9e sur la partie droite du quart inf\u00e9rieur droit de la composition, il porte livre et plume.\u00a0Mata Linares \u00e9tait issu d\u2019une famille \u00e9minente de fonctionnaires, son p\u00e8re \u00e9tait membre du Conseil de Castille. Mata Linares, apr\u00e8s avoir \u00e9tudi\u00e9 et enseign\u00e9 en Espagne est promu au tribunal de Lima et en 1781. Il pr\u00e9side le proc\u00e8s de T\u00fapac Amaru II. La s\u00e9v\u00e9rit\u00e9 des peines prononc\u00e9es lui a valu une r\u00e9putation de cruaut\u00e9, r\u00e9putation renforc\u00e9e par les tortures qu\u2019il a inflig\u00e9es par la suite (ill. 19).<\/li>\n<\/ul>\n<ul>\n<li>Le troisi\u00e8me et dernier, le mar\u00e9chal don Jos\u00e9 Del Valle, debout sur la gauche de la porte du four, est figur\u00e9 au coin inf\u00e9rieur droit de la composition sous les traits d\u2019un condamn\u00e9 qu\u2019un d\u00e9mon agresse. Ce mar\u00e9chal \u00a0d\u00e9fait l\u2019arm\u00e9e de Tupac Amaru II \u00e0 la t\u00eate de cinquante mille hommes le 2 janvier 1781\u00a0\u00e0 Cuzco (ill. 20).<\/li>\n<\/ul>\n<p>F\u00e9ru de la civilisation inca, Juan Manuel Cardenas-Castro a fait force lectures, et tout comme \u00a0Tadeo Escalante, il connaissait les sources anciennes. Cette \u0153uvre, <em>Sinchi Roca 2e Inca<\/em>, d&rsquo;une s\u00e9rie de douze, peint sur toile, semble directement n\u00e9 de l\u2019inspiration fertile et narrative forte de ce grand ain\u00e9.<\/p>\n\n\t\t<style>\n\t\t\t#gallery-6 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-6 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-6 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-6 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div data-carousel-extra='{&quot;blog_id&quot;:1,&quot;permalink&quot;:&quot;https:\/\/alaincardenas.com\/blog\/portraits-dhier-et-de-demain-3-de-la-peinture-murale-peruvienne-a-propos-de-deux-oeuvres-tadeo-escalante-muraliste-du-sud-andin-1\/&quot;}' id='gallery-6' class='gallery galleryid-5118 gallery-columns-2 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/alaincardenas.com\/blog\/portraits-dhier-et-de-demain-3-de-la-peinture-murale-peruvienne-a-propos-de-deux-oeuvres-tadeo-escalante-muraliste-du-sud-andin-1\/18-2-inca-sinchi-roca-dsc_0048-bd\/'><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"900\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/18-2-inca-sinchi-roca-DSC_0048-BD.jpg?fit=683%2C900&amp;ssl=1\" class=\"attachment-full size-full\" alt=\"\" aria-describedby=\"gallery-6-5137\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/18-2-inca-sinchi-roca-DSC_0048-BD.jpg?w=683&amp;ssl=1 683w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/18-2-inca-sinchi-roca-DSC_0048-BD.jpg?resize=228%2C300&amp;ssl=1 228w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" data-attachment-id=\"5137\" data-permalink=\"https:\/\/alaincardenas.com\/blog\/portraits-dhier-et-de-demain-3-de-la-peinture-murale-peruvienne-a-propos-de-deux-oeuvres-tadeo-escalante-muraliste-du-sud-andin-1\/18-2-inca-sinchi-roca-dsc_0048-bd\/\" data-orig-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/18-2-inca-sinchi-roca-DSC_0048-BD.jpg?fit=683%2C900&amp;ssl=1\" data-orig-size=\"683,900\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;NIKON D3200&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1562515937&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;25&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.004&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;\u00a0(ill. 21) Juan Manuel Cardenas-Castro. Sinchi Roca 2e Inca (ca 1970), huile sur toile, 65 x 50 cm (coll. priv\u00e9e)&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/18-2-inca-sinchi-roca-DSC_0048-BD.jpg?fit=584%2C770&amp;ssl=1\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-6-5137'>\n\t\t\t\t\u00a0(ill. 21) Juan Manuel Cardenas-Castro. Sinchi Roca 2e Inca (ca 1970), huile sur toile, 65 x 50 cm (coll. priv\u00e9e)\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/alaincardenas.com\/blog\/portraits-dhier-et-de-demain-3-de-la-peinture-murale-peruvienne-a-propos-de-deux-oeuvres-tadeo-escalante-muraliste-du-sud-andin-1\/dsc_4072-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"473\" height=\"358\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/DSC_4072-1.jpg?fit=473%2C358&amp;ssl=1\" class=\"attachment-full size-full\" alt=\"\" aria-describedby=\"gallery-6-5186\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/DSC_4072-1.jpg?w=473&amp;ssl=1 473w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/DSC_4072-1.jpg?resize=300%2C227&amp;ssl=1 300w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/DSC_4072-1.jpg?resize=396%2C300&amp;ssl=1 396w\" sizes=\"auto, (max-width: 473px) 100vw, 473px\" data-attachment-id=\"5186\" data-permalink=\"https:\/\/alaincardenas.com\/blog\/portraits-dhier-et-de-demain-3-de-la-peinture-murale-peruvienne-a-propos-de-deux-oeuvres-tadeo-escalante-muraliste-du-sud-andin-1\/dsc_4072-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/DSC_4072-1.jpg?fit=473%2C358&amp;ssl=1\" data-orig-size=\"473,358\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;F3311&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1570978239&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.5&quot;,&quot;iso&quot;:&quot;3141&quot;,&quot;shutter_speed&quot;:&quot;0.04999500049995&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;(ill. 22) Tadeo escalante. Peinture murale des Incas (2e quart du XVIIIe s.), Moulin des Incas, Acomayo, P\u00e9rou&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/06\/DSC_4072-1.jpg?fit=473%2C358&amp;ssl=1\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-6-5186'>\n\t\t\t\t(ill. 22) Tadeo escalante. Peinture murale des Incas (2e quart du XVIIIe s.), Moulin des Incas, Acomayo, P\u00e9rou\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a>Le muralisme mexicain est un mouvement artistique qui s&rsquo;est d\u00e9velopp\u00e9 au Mexique suite \u00e0 la r\u00e9volution mexicaine de 1910. Les trois artistes les plus influents associ\u00e9s \u00e0 ce mouvement sont Diego Rivera, Jos\u00e9 Clemente Orozco et David Alfaro Siqueiros.<\/p>\n<p><a href=\"#_ftnref2\" name=\"_ftn2\">[2]<\/a> La grotte orn\u00e9e de Toquepala (Tacna) est dat\u00e9e entre &#8211; 12 000 \u00e0 &#8211; 10 000 av. J.-C.<\/p>\n<p><a href=\"#_ftnref3\" name=\"_ftn3\">[3]<\/a> Avant la conqu\u00eate espagnole, l\u2019Empire inca s\u2019appelait <em>Tawantinsuyu<\/em>\u00a0: les Quatre-R\u00e9gions-Unies (en langue quechua, <em>tawa<\/em>\u00a0: quatre, &#8211;<em>ntin<\/em>\u00a0: ensemble, <em>suyu<\/em>\u00a0: r\u00e9gion). Le <em>Tawantinsuyu\u00a0<\/em> \u00e9tait divis\u00e9 en quatre parties d\u00e9nomm\u00e9es <em>Chinchasuyu<\/em>, <em>Antisuyu<\/em>, <em>Collasuyu<\/em>, <em>Cuntisuyu<\/em>. Ces quatre parties s\u2019\u00e9tendaient sur les actuels Colombie, Chili, Bolivie, Argentine P\u00e9rou et \u00c9quateur.<\/p>\n<p><a href=\"#_ftnref4\" name=\"_ftn4\">[4]<\/a> Cet administrateur indig\u00e8ne organise \u00ab\u00a0La Grande R\u00e9bellion\u00a0\u00bb de 1780 contre la domination espagnole en prenant le nom de T\u00fapac Amaru II \u2014 en l\u2019honneur de son anc\u00eatre, T\u00fapac Amaru, le dernier inca de Vilcabamba.<\/p>\n<p><a href=\"#_ftnref5\" name=\"_ftn5\">[5]<\/a> Les mesures prises par l\u2019inspecteur d\u2019administration repr\u00e9sentant du pouvoir colonial dans la vice-royaut\u00e9 du P\u00e9rou, Jos\u00e9 Antonio de Areche Zornoza (1731-1789), ont fait l\u2019objet de diff\u00e9rents textes dont l\u2019un est reproduit en annexe.<\/p>\n<p><a href=\"#_ftnref6\" name=\"_ftn6\">[6]<\/a> Sur une carte publi\u00e9e par Alberto Flores Galindo, Acomayo et Huaro apparaissent comme des localit\u00e9s partisanes de la <em>Grande Rebellion<\/em> (Flores Galindo, 1988\u00a0: 135).<\/p>\n<p><a href=\"#_ftnref7\" name=\"_ftn7\">[7]<\/a> Pablo Macera, <em>Pintores populares andinos<\/em>, Banco de los Andes, Lima 1979.<\/p>\n<p><a href=\"#_ftnref8\" name=\"_ftn8\">[8]<\/a> Les <em>Comentarios Reales de los Incas<\/em> (Lisbonne, 1609) est un ouvrage qui a \u00e9t\u00e9 r\u00e9dig\u00e9 par le chroniqueur m\u00e9tis, l\u2019<em>Inca Garcilaso de la Vega<\/em> (1539-1616) sur tout ce qui concerne l&#8217;empire Inca, de sa naissance \u00e0 sa destruction. Ce livre relate \u00e9galement tous les aspects de la soci\u00e9t\u00e9 inca. Il est consid\u00e9r\u00e9 comme un plaidoyer adress\u00e9 \u00e0 la Couronne d&rsquo;Espagne afin que les sujets Indiens du royaume d&rsquo;Espagne soient consid\u00e9r\u00e9s comme des sujets l\u00e9gitimes du royaume, titulaires des m\u00eames droits que les colons espagnols.<\/p>\n<p><a href=\"#_ftnref9\" name=\"_ftn9\">[9]<\/a> <em>La Historia general de los hechos de los castellanos en las Islas y Tierra Firme del mar Oc\u00e9ano que llaman Indias Occidentales<\/em> connue aussi comme la <em>D\u00e9cadas de Indias <\/em>d\u2019Antonio de Herrera y Tordesillas, chroniqueur des rois Felipe II et Felipe III d\u2019Espagne a \u00e9t\u00e9 publi\u00e9e \u00e0 Madrid entre 1601 et 1615 en 4 vol.<\/p>\n<p><a href=\"#_ftnref10\" name=\"_ftn10\">[10]<\/a> Reine ou fille de reine en langue quechua.<\/p>\n<p><a href=\"#_ftnref11\" name=\"_ftn11\">[11]<\/a> Notes prises lors de rencontres avec Nicol\u00e1s Escalante durant ma mission de recherche au P\u00e9rou en 2019.<\/p>\n<p><a href=\"#_ftnref12\" name=\"_ftn12\">[12]<\/a> V\u00e9n\u00e9r\u00e9 par les fid\u00e8les en p\u00e8lerinage \u00e0 Saint Jacques de Compostelle, Jacques Saint galil\u00e9en, l\u2019ap\u00f4tre \u00e9vang\u00e9lisateur de l\u2019Espagne selon une l\u00e9gende du XII<sup>e<\/sup> s. est martyris\u00e9 lors de son retour \u00e0 J\u00e9rusalem. Son corps est achemin\u00e9 en Espagne par ses disciples\u00a0; son tombeau pr\u00e9sum\u00e9 est \u00e0 l\u2019origine de la ville et du p\u00e8lerinage de Compostelle et de l\u2019image du saint p\u00e8lerin. Il devient le saint combattant r\u00e9v\u00e9r\u00e9 au IX<sup>e<\/sup> s. et pendant les Croisades. L\u2019iconographie refl\u00e8te la pr\u00e9sence d\u2019un soldat de Dieu combattant au nom de la Foi. Elle devient celle d\u2019un tueur de Maures, puis d\u2019Indiens et ensuite de Turcs. Quant \u00e0 l\u2019image du saint Jacques Matamore, elle date du XIV<sup>e<\/sup> s. Sept si\u00e8cles apr\u00e8s l\u2019invasion musulmane, l\u2019image du Saint Jacques Matamore appara\u00eet. L\u2019origine du mot Matamoros se rattache au surnom d\u2019un valeureux soldat ayant lutt\u00e9 contre les Maures. Cervantes dans le <em>Don Quichotte<\/em> publi\u00e9 en 1615 r\u00e9unit des deux mots <em>Santiago<\/em> et <em>Matamoros<\/em>. Le mot et l\u2019image du noble chevalier de Castille venant en aide aux chevaliers de l\u2019Ordre de Santiago ont \u00e9t\u00e9 utilis\u00e9s par les Conquistadors. Il devient alors le tueurs d\u2019indiens le <em>Mataindios<\/em> en Am\u00e9rique latine.<\/p>\n<p><a href=\"#_ftnref13\" name=\"_ftn13\">[13]<\/a> Idem<\/p>\n<p><a href=\"#_ftnref14\" name=\"_ftn14\">[14]<\/a> Tadeo Escalante aurait assist\u00e9 \u00e0 l\u2019ex\u00e9cution de Tupac Amaru II et de l&rsquo;\u00e9pouse de ce dernier, Micaela Bastida, et des autres participants de la r\u00e9bellion indig\u00e8ne de 1780. Cette ex\u00e9cution sanglante au cours de laquelle les rebelles ont \u00e9t\u00e9 \u00e9cartel\u00e9s et d\u00e9membr\u00e9s pour que leurs corps soient r\u00e9partis aux quatre coins du pays aurait marqu\u00e9 profond\u00e9ment Tadeo Escalante et aurait \u00e9t\u00e9 d\u00e9terminante pour sont ralliement \u00e0 la cause rebelle.<\/p>\n<p><a href=\"#_ftnref15\" name=\"_ftn15\">[15]<\/a> En 1571, le cinqui\u00e8me Vice-roi du P\u00e9rou, Francisco de Toledo, commande \u00e0 des peintres indig\u00e8nes une s\u00e9rie de peintures, dont les portraits dynastiques des Incas, pour en faire cadeau \u00e0 Philippe II afin de le documenter sur l\u2019Histoire et les coutumes des Incas. Ces toiles, d\u00e9truites dans l\u2019incendie de <em>la Casa del Tesoro<\/em> en 1734, \u00e0 Madrid, sont rest\u00e9es les mod\u00e8les visuels \u00e0 suivre, entre autres, pour l\u00e9gitimer les proc\u00e9dures l\u00e9gales de successions g\u00e9n\u00e9alogiques pour la Couronne espagnole et l\u2019aristocratie indig\u00e8ne.<\/p>\n<p><a href=\"#_ftnref16\" name=\"_ftn16\">[16]<\/a> Fr\u00e8re Martin de Mur\u00faa est n\u00e9 au Pays Basque entre 1525 et 1535. Il appartient \u00e0 l\u2019ordre de la Merci dont il fut \u00e9lecteur g\u00e9n\u00e9ral pour la province du P\u00e9rou \u00e0 partir de 1560. A partir de 1590, il se partage entre Arequipa et Cusco o\u00f9 il s\u2019\u00e9tablit en 1606. Il finit de r\u00e9diger son <em>Histoire g\u00e9n\u00e9rale du P\u00e9rou<\/em> en 1613.<\/p>\n<p><a href=\"#_ftnref17\" name=\"_ftn17\">[17]<\/a> Vase tronconique \u00e0 usage c\u00e9r\u00e9moniel, selon les investigations arch\u00e9ologiques les mat\u00e9riaux utilis\u00e9s sont l&rsquo;or, l&rsquo;argent, le cuivre, le bronze, la c\u00e9ramique et le bois. Le <em>kero<\/em> du quechua <em>qiru<\/em>, s\u2019\u00e9crit \u00e9galement <em>quero<\/em> ou <em>qero<\/em>. Cette tradition d\u2019objet liturgique inca se poursuit sous le gouvernement colonial espagnol. La forme pr\u00e9-inca remonte \u00e0 plus de mille ans avant J.-C. Quant \u00e0 la forme cylindrique, une bouche \u00e9largie, elle se poursuit avec un corps qui se r\u00e9tr\u00e9cit \u00e0 la mani\u00e8re d&rsquo;un sablier pour s&rsquo;\u00e9largir \u00e0 la base. La tradition inca de cette fabrication n&rsquo;a pas \u00e9t\u00e9 interrompue, elle s&rsquo;est poursuivie \u00e0 l\u2019\u00e9poque coloniale avec la r\u00e9alisation de pi\u00e8ces peintes \u00e0 th\u00e8mes vari\u00e9s : vie quotidienne, activit\u00e9s agricoles et d&rsquo;\u00e9levage\u00a0; affrontements guerriers entre les Incas et d&rsquo;autres groupes ethniques ainsi qu&rsquo;avec les Espagnols.<\/p>\n<p><a href=\"#_ftnref18\" name=\"_ftn18\">[18]<\/a> Jos\u00e9 Uriel Garc\u00eda Ochoa (1894-1965) est un intellectuel et enseignant p\u00e9ruvien. Il participe aux fondements du mouvement indig\u00e9niste au P\u00e9rou.<\/p>\n<p><a href=\"#_ftnref19\" name=\"_ftn19\">[19]<\/a> Les r\u00e9formes \u00e9tablies par Jos\u00e9 Antonio de Areche Zornoza (1731-1789) ont suscit\u00e9 la <em>Grande R\u00e9bellion<\/em> men\u00e9e par le chef quechua Jos\u00e9 Gabriel Condorcanqui (Tupac Amaru II). Le texte de ces r\u00e9formes est donn\u00e9 en annexe ci-apr\u00e8s. Par ailleurs, la duret\u00e9 de cette r\u00e9pression, ajout\u00e9e \u00e0 ses d\u00e9m\u00eal\u00e9s avec le vice-roi Guirior, ont provoqu\u00e9 la disgr\u00e2ce de Areche et le rappel de cet administrateur colonial en Espagne.<\/p>\n<p><strong><span style=\"color: #800000;\">Annexe<\/span><\/strong><\/p>\n<p>Apr\u00e8s que la <em>Grande R\u00e9bellion<\/em>\u00a0contre les indig\u00e8nes ait \u00e9t\u00e9 mat\u00e9e par les militaires, Jos\u00e9 Antonio de Areche Zornoza (1731-1789) a d\u00e9cr\u00e9ter les mesures suivantes : \u00ab\u00a0<em>interdiction pour les indig\u00e8nes de porter des v\u00eatements traditionnels, et ordre de confiscation de ceux-ci ; ordre de d\u00e9truire toute peinture repr\u00e9sentant les empereurs incas, que ce soit en public ou en priv\u00e9, y compris dans les domiciles des particuliers ; prohibition de pi\u00e8ces de th\u00e9\u00e2tre ou d\u2019autres manifestations publiques organis\u00e9es en comm\u00e9moration des Incas, avec obligation pour les fonctionnaires espagnols de faire rapport officiel sur les progr\u00e8s de cette suppression ; proscription des trompettes et cors (constitu\u00e9s de coquillages) traditionnels, au motif que leur son triste \u00e9quivalait \u00e0 une fa\u00e7on de deuil pour les anc\u00eatres et les temps anciens ; interdiction \u00e0 quiconque de se donner le nom d\u2019Inca (dans l\u2019acception d\u2019empereur ou de dynastie royale, non de l\u2019ethnie indienne) ; obligation pour les \u00e9coles d\u2019enseigner le castillan aux Indiens, et pour les Indiens de les fr\u00e9quenter ; interdiction de confectionner des armes, sous peine d\u2019emprisonnement de 10 ans en Afrique en sus (pour les manants) de 200 coups de fouet\u00a0<\/em>\u00bb\u00a0(The Tupac Amaru Rebellion, Charles F. Walker, p. 163).<\/p>\n<p>Par ailleurs, en avril 1782, le roi Charles III, sur les instances du visitador Areche, donna ordre aux officiels vice-royaux du P\u00e9rou et du R\u00edo de la Plata de saisir tout exemplaire des <em>Commentaires royaux<\/em> de l\u2019Inca Garcilaso de la Vega qu\u2019ils d\u00e9couvriraient ; cet ouvrage, paru pour la premi\u00e8re fois en 1609, \u00e9tait suppos\u00e9 renfermer une proph\u00e9tie annon\u00e7ant la r\u00e9bellion de T\u00fapac Amaru II.<\/p>\n<p><strong><span style=\"color: #800000;\">Bibliographie<\/span><\/strong><\/p>\n<ul>\n<li>Jorge A. Flores Ochoa, Elizabeth Kuon Arce, Roberto Samanez Argumedo. Pintura Mural en el Sur Andino, Collecci\u00f3n Arte Tesoros Del Per\u00fa, Banco de cr\u00e9dito del Per\u00fa, Lima, 1993, 359 p.<\/li>\n<li>P\u00e9ricard-M\u00e9a, \u00abSaint Jacques, de l\u2019ap\u00f4tre au Matamore\u00bb, <em>SaintJacquesInfo<\/em> [En ligne], Saint Jacques un et multiple, Le saint politique, mis \u00e0 jour le : 22\/02\/2016, URL : http:\/\/lodel.irevues.inist.fr\/saintjacquesinfo\/index.php?id=1334<\/li>\n<li>Martin, Rossella. \u202a\u00ab\u00a0L\u2019image du sauvage dans le th\u00e9\u00e2tre quechua et l\u2019iconographie des queros (P\u00e9rou, XVII-XVIII)\u00a0\u00bb,\u00a0<em>Corpus<\/em> [En l\u00ednea], Vol 4, No 2\u00a0|\u00a02014, Publicado el \u202a19 diciembre 2014, consultado el \u202a09 junio 2020. \u202aURL : http:\/\/journals.openedition.org\/corpusarchivos\/1236\u00a0; \u202aDOI\u00a0: https:\/\/doi.org\/10.4000\/corpusarchivos.1236<\/li>\n<li><strong>\u202a<\/strong>Cohen Suarez, Ananda. <em>Heaven, Hell, and Everything in Between: Murals of the Colonial Andes<\/em>, University of Texas press, 2016, 304 p.<\/li>\n<li>Le\u00f3n Fern\u00e1ndez, Dino. <em>Trabajos de historia: religi\u00f3n, cultura y pol\u00edtica en el Per\u00fa, siglos XVII-XX<\/em>, Universidad nacional mayor de San Marcos, Lima 2011, 353 p.<\/li>\n<li>Flores Ochoa, Jorge ; Kuon, Elizabeth y Roberto Samanez, <em>Arte inka en vasos ceremoniales<\/em>, Banco de Cr\u00e9dito del Per\u00fa, 1998, Lima.<\/li>\n<li>\n<div><span dir=\"ltr\">Walker, Charles F. <em>The Tupac Amaru Rebellion<\/em>,\u00a0<\/span><span dir=\"ltr\">Harvard University Press<\/span>,\u00a0<span dir=\"ltr\">2014,\u00a0<\/span><span dir=\"ltr\">373 p.<\/span><\/div>\n<\/li>\n<li>Uriel Garc\u00eda,\u00a0Jos\u00e9. \u00ab\u00a0Escuela cuzque\u00f1a de arte colonial, la iglesia de Hu\u00e1roc\u00a0\u00bb, <em>Cuadernos americanos<\/em> n\u00b0 2, (1963), pp. 162-182.<\/li>\n<li>Macera, Pablo.\u00a0<em>Pintores populares andinos<\/em>, Banco de los Andes, Lima 1979.<\/li>\n<li>Bravo Paredes, Ligia Abigail. <em>La colonizaci\u00f3n del imaginario ind\u00edgena: Una interpretaci\u00f3n del arte mural de la iglesia de San Juan de Huaro<\/em>, Tesis en Antropolog\u00eda, Universidad Nacional de San Antonio Abad del Cusco, 2015<\/li>\n<li>Cardenas-Castro, Alain. <a href=\"https:\/\/wp.me\/p8Mijt-Mf\"><em>Jorge Luis Chirinos V\u00e1squez. Un mural de Jorge Luis Chirinos V\u00e1squez, \u00ab\u00a0Pass\u00e9, pr\u00e9sent et futur de la M\u00e9decine\u00a0\u00bb\u00a0: propos sur la peinture murale cuzqu\u00e9nienne<\/em><\/a> in blog\u00a0: Sciences &amp; art contemporain IN &#8211; MH &#8211; OUT \u2013 OFF, publi\u00e9 le 29 janvier 2019<\/li>\n<\/ul>\n<p>Remerciements<\/p>\n<p>Marie Akar, Paola Mattos, Gioconda Mercado, Martine Vall\u00e9e, Alvaro Castro Gutierrez, Jos\u00e9 Castro Gutierrez, Jorge Chirinos, Nicol\u00e1s Escalante, Enrique Leon Maristany<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rapport\u00a0succinct d&rsquo;une mission de recherche men\u00e9e en octobre 2019 dans la r\u00e9gion de Cuzco. Durant ce s\u00e9jour de recherche, l&rsquo;auteur a pu fournir un ensemble de photographies in\u00e9dites. L&rsquo;acc\u00e8s parfois difficile aux lieux n&rsquo;a pas pu permettre une qualit\u00e9 toujours &hellip; <a href=\"https:\/\/alaincardenas.com\/blog\/portraits-dhier-et-de-demain-3-de-la-peinture-murale-peruvienne-a-propos-de-deux-oeuvres-tadeo-escalante-muraliste-du-sud-andin-1\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[43,42,1,22],"tags":[9,33,38],"class_list":["post-5118","post","type-post","status-publish","format-standard","hentry","category-amerique-latine","category-europe","category-oeuvre","category-portrait","tag-arts-plastiques","tag-collection","tag-oeuvre"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8Mijt-1ky","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":6019,"url":"https:\/\/alaincardenas.com\/blog\/du-bon-usage-de-lappui-a-la-recherche\/","url_meta":{"origin":5118,"position":0},"title":"Du bon usage de l\u2019appui \u00e0 la recherche","author":"admin","date":"2021-11-30","format":false,"excerpt":"A propos de la th\u00e8se d\u2019Alain Cardenas-Castro, Cr\u00e9ation artistique et donn\u00e9es ethno-anthropologiques p\u00e9ruviennes. 1915-2015 : une lign\u00e9e de peintres mus\u00e9ographes, les Cardenas-Castro. Afin de donner davantage d\u2019informations sur la soutenance de th\u00e8se en esthe\u0301tique, sciences et technologies des arts, spe\u0301cialite\u0301 arts plastiques et photographie,\u00a0pass\u00e9e et obtenue avec succ\u00e8s \u00e0 l\u2019universit\u00e9\u2026","rel":"","context":"Dans &quot;Am\u00e9rique latine&quot;","block_context":{"text":"Am\u00e9rique latine","link":"https:\/\/alaincardenas.com\/blog\/category\/amerique-latine\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2021\/11\/ChC-3.jpeg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2021\/11\/ChC-3.jpeg?resize=350%2C200 1x, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2021\/11\/ChC-3.jpeg?resize=525%2C300 1.5x"},"classes":[]},{"id":2991,"url":"https:\/\/alaincardenas.com\/blog\/un-mural-de-jorge-luis-chirinos-vasquez-passe-present-et-futur-de-la-medecine-propos-sur-la-peinture-murale-cuzquenienne\/","url_meta":{"origin":5118,"position":1},"title":"Un mural de Jorge Luis Chirinos V\u00e1squez, \u00ab\u00a0Pass\u00e9, pr\u00e9sent et futur de la M\u00e9decine\u00a0\u00bb\u00a0: propos sur la peinture murale cuzqu\u00e9nienne.","author":"admin","date":"2019-01-29","format":false,"excerpt":"par Alain Cardenas-Castro et Jorge Luis Chirinos V\u00e1squez En descendant l\u2019avenue de la Culture depuis l\u2019Universit\u00e9 San Antonio Abad, on peut longer le mur d\u2019enceinte de l\u2019H\u00f4pital r\u00e9gional de Cusco et d\u00e9couvrir cette peinture monumentale intitul\u00e9e Pass\u00e9, pr\u00e9sent et futur de la M\u00e9decine. Ce mural a \u00e9t\u00e9 r\u00e9alis\u00e9 pour comm\u00e9morer\u2026","rel":"","context":"Dans &quot;Am\u00e9rique latine&quot;","block_context":{"text":"Am\u00e9rique latine","link":"https:\/\/alaincardenas.com\/blog\/category\/amerique-latine\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2019\/01\/DSC_1711-copie.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2019\/01\/DSC_1711-copie.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2019\/01\/DSC_1711-copie.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2019\/01\/DSC_1711-copie.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2019\/01\/DSC_1711-copie.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2019\/01\/DSC_1711-copie.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":8248,"url":"https:\/\/alaincardenas.com\/blog\/entre-urdimbres-y-tramas-cristina-ghetti\/","url_meta":{"origin":5118,"position":2},"title":"Entre urdimbres y tramas, Cristina Ghetti","author":"admin","date":"2024-09-20","format":false,"excerpt":"Exposition du 15 septembre au 19 octobre 2024, Galerie Younique *,\u00a065 rue Pascal 75013 Paris, du jeudi au samedi de 16h \u00e0 20h et sur RDV. compte-rendu par Alain Cardenas-Castro Cristina Ghetti est une artiste argentine qui vit et travaille \u00e0 Valence, en Espagne. Depuis une dizaine d'ann\u00e9es, elle s'int\u00e9resse\u2026","rel":"","context":"Dans &quot;Am\u00e9rique latine&quot;","block_context":{"text":"Am\u00e9rique latine","link":"https:\/\/alaincardenas.com\/blog\/category\/amerique-latine\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2024\/09\/1726853216332.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2024\/09\/1726853216332.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2024\/09\/1726853216332.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2024\/09\/1726853216332.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2024\/09\/1726853216332.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":3697,"url":"https:\/\/alaincardenas.com\/blog\/de-la-linogravure-appliquee-a-mes-estampes-a-mes-livres-et-aux-peintures\/","url_meta":{"origin":5118,"position":3},"title":"De la linogravure appliqu\u00e9e \u00e0 mes estampes, \u00e0 mes livres et aux peintures","author":"admin","date":"2019-06-30","format":false,"excerpt":"par Alain Cardenas-Castro L\u2019histoire de cette technique et de ce mat\u00e9riau renvoie \u00e0 des p\u00e9riodes et \u00e0 des lieux autres. J\u2019ai privil\u00e9gi\u00e9 mon parcours et les rencontres avec des \u0153uvres de divers cr\u00e9ateurs comme Pablo Picasso ou Manuel Fiorini comme autant Leopoldo M\u00e9ndez ou Charles-Hossein Zenderoudi. J\u2019ai adapt\u00e9 ce mat\u00e9riau\u2026","rel":"","context":"Dans &quot;Am\u00e9rique latine&quot;","block_context":{"text":"Am\u00e9rique latine","link":"https:\/\/alaincardenas.com\/blog\/category\/amerique-latine\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2019\/06\/01-Fiorini-1963-150x150.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":9618,"url":"https:\/\/alaincardenas.com\/blog\/javier-silva-meinel\/","url_meta":{"origin":5118,"position":4},"title":"Javier Silva Meinel","author":"admin","date":"2026-05-10","format":false,"excerpt":"Umbrales [Seuils]. Une po\u00e9tique de l\u2019image par Alain Cardenas-Castro PARUTION Livre-Catalogue \/ Libro-Cat\u00e1logo. \u00ab\u00a0Depuis plus de quatre d\u00e9cennies Silva Meinel n'a cess\u00e9 de parcourir les c\u00f4tes du Pacifique, les montagnes des Andes et la for\u00eat amazonienne \u00e0 la recherche de signes, d'interstices, de scintillements, d'\u00e9piphanies qui invitent le regardeur \u00e0\u2026","rel":"","context":"Dans &quot;Am\u00e9rique latine&quot;","block_context":{"text":"Am\u00e9rique latine","link":"https:\/\/alaincardenas.com\/blog\/category\/amerique-latine\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2026\/05\/IMG_20260428_122514.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":7137,"url":"https:\/\/alaincardenas.com\/blog\/images-et-representations-du-perou-en-france-1821-2021\/","url_meta":{"origin":5118,"position":5},"title":"Images et repr\u00e9sentations du P\u00e9rou en France (1821-2021)","author":"admin","date":"2023-05-29","format":false,"excerpt":"par Alain Cardenas-Castro J\u2019ai, voil\u00e0 une ann\u00e9e, \u00e9prouv\u00e9 la n\u00e9cessit\u00e9 de faire le point sur le colloque international, \u00ab\u00a0Images et repr\u00e9sentations du P\u00e9rou en France \u2013 1821-2021\u00a0\u00bb qui s\u2019est tenu au Mus\u00e9e d\u2019Aquitaine sis \u00e0 Bordeaux le vendredi 12 et le samedi 13 novembre 2021 (voir le blog Sciences et\u2026","rel":"","context":"Dans &quot;Am\u00e9rique latine&quot;","block_context":{"text":"Am\u00e9rique latine","link":"https:\/\/alaincardenas.com\/blog\/category\/amerique-latine\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/Images-Perou-couverture-4eme_page-0001.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/Images-Perou-couverture-4eme_page-0001.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/Images-Perou-couverture-4eme_page-0001.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/Images-Perou-couverture-4eme_page-0001.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2023\/05\/Images-Perou-couverture-4eme_page-0001.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/posts\/5118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/comments?post=5118"}],"version-history":[{"count":39,"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/posts\/5118\/revisions"}],"predecessor-version":[{"id":8800,"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/posts\/5118\/revisions\/8800"}],"wp:attachment":[{"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/media?parent=5118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/categories?post=5118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/tags?post=5118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}