{"id":6559,"date":"2022-09-18T09:36:42","date_gmt":"2022-09-18T07:36:42","guid":{"rendered":"https:\/\/alaincardenas.com\/blog\/wp-content\/uploads\/2022\/09\/R.Seneque-39-caracte\u0300res-sept-22.jpg"},"modified":"2022-09-18T09:36:42","modified_gmt":"2022-09-18T07:36:42","slug":"r-seneque-39-caracteres-sept-22","status":"inherit","type":"attachment","link":"https:\/\/alaincardenas.com\/blog\/propos-de-calligraphie-contemporaine-2-quelques-reflexions-automnales\/r-seneque-39-caracteres-sept-22\/","title":{"rendered":"R.Seneque, 39 caracte\u0300res sept 22"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-6559","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/a8Mijt-1HN","jetpack_likes_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2022\/09\/R.Seneque-39-caracte%CC%80res-sept-22.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"202\" height=\"300\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2022\/09\/R.Seneque-39-caracte%CC%80res-sept-22.jpg?fit=202%2C300&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" data-attachment-id=\"6559\" data-permalink=\"https:\/\/alaincardenas.com\/blog\/propos-de-calligraphie-contemporaine-2-quelques-reflexions-automnales\/r-seneque-39-caracteres-sept-22\/\" data-orig-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2022\/09\/R.Seneque-39-caracte%CC%80res-sept-22.jpg?fit=690%2C1024&amp;ssl=1\" data-orig-size=\"690,1024\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 6D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1662747900&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;53&quot;,&quot;iso&quot;:&quot;125&quot;,&quot;shutter_speed&quot;:&quot;0.5&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"R.Seneque, 39 caracte\u0300res sept 22\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2022\/09\/R.Seneque-39-caracte%CC%80res-sept-22.jpg?fit=584%2C867&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":690,"height":1024,"file":"2022\/09\/R.Seneque-39-caracte\u0300res-sept-22.jpg","sizes":{"thumbnail":{"file":"R.Seneque-39-caracte\u0300res-sept-22-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2022\/09\/R.Seneque-39-caracte%CC%80res-sept-22.jpg?resize=150%2C150&ssl=1"},"medium":{"file":"R.Seneque-39-caracte\u0300res-sept-22-202x300.jpg","width":202,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2022\/09\/R.Seneque-39-caracte%CC%80res-sept-22.jpg?fit=202%2C300&ssl=1"},"large":{"file":"R.Seneque-39-caracte\u0300res-sept-22-690x1024.jpg","width":690,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2022\/09\/R.Seneque-39-caracte%CC%80res-sept-22.jpg?fit=584%2C867&ssl=1"},"post-thumbnail":{"file":"R.Seneque-39-caracte\u0300res-sept-22-690x288.jpg","width":690,"height":288,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2022\/09\/R.Seneque-39-caracte%CC%80res-sept-22.jpg?resize=690%2C288&ssl=1"},"large-feature":{"file":"R.Seneque-39-caracte\u0300res-sept-22-690x288.jpg","width":690,"height":288,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2022\/09\/R.Seneque-39-caracte%CC%80res-sept-22.jpg?resize=690%2C288&ssl=1"},"small-feature":{"file":"R.Seneque-39-caracte\u0300res-sept-22-202x300.jpg","width":202,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2022\/09\/R.Seneque-39-caracte%CC%80res-sept-22.jpg?fit=202%2C300&ssl=1"},"full":{"file":"R.Seneque-39-caracte%CC%80res-sept-22.jpg?fit=690%2C1024&ssl=1","width":690,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2022\/09\/R.Seneque-39-caracte%CC%80res-sept-22.jpg?fit=690%2C1024&ssl=1"}},"image_meta":{"aperture":"8","credit":"","camera":"Canon EOS 6D","caption":"","created_timestamp":"1662747900","copyright":"","focal_length":"53","iso":"125","shutter_speed":"0.5","title":"","orientation":"1","keywords":[]}},"post":6553,"source_url":"https:\/\/alaincardenas.com\/blog\/wp-content\/uploads\/2022\/09\/R.Seneque-39-caracte\u0300res-sept-22.jpg","filename":"R.Seneque-39-caracte\u0300res-sept-22.jpg","filesize":116037,"_links":{"self":[{"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/media\/6559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/comments?post=6559"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":6553,"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/posts\/6553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}