{"id":4848,"date":"2020-03-19T07:49:55","date_gmt":"2020-03-19T06:49:55","guid":{"rendered":"https:\/\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/03\/Guaman-Poma-de-Ayala-BD.jpg"},"modified":"2020-03-19T15:20:51","modified_gmt":"2020-03-19T14:20:51","slug":"guaman-poma-de-ayala-bd","status":"inherit","type":"attachment","link":"https:\/\/alaincardenas.com\/blog\/portraits-dhier-et-de-demain-1-juan-diego-vergara-ormeno-le-plasticien-peruvien\/guaman-poma-de-ayala-bd\/","title":{"rendered":"(ill. 11)"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-4848","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/a8Mijt-1gc","jetpack_likes_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/03\/Guaman-Poma-de-Ayala-BD.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"185\" height=\"300\" src=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/03\/Guaman-Poma-de-Ayala-BD.jpg?fit=185%2C300&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/03\/Guaman-Poma-de-Ayala-BD.jpg?w=370&amp;ssl=1 370w, https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/03\/Guaman-Poma-de-Ayala-BD.jpg?resize=185%2C300&amp;ssl=1 185w\" sizes=\"auto, (max-width: 185px) 100vw, 185px\" data-attachment-id=\"4848\" data-permalink=\"https:\/\/alaincardenas.com\/blog\/portraits-dhier-et-de-demain-1-juan-diego-vergara-ormeno-le-plasticien-peruvien\/guaman-poma-de-ayala-bd\/\" data-orig-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/03\/Guaman-Poma-de-Ayala-BD.jpg?fit=370%2C600&amp;ssl=1\" data-orig-size=\"370,600\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 6s&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1584541270&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.15&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"(ill. 11)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;(ill. 12)&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/03\/Guaman-Poma-de-Ayala-BD.jpg?fit=370%2C600&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>(ill. 12) <a href=\"https:\/\/alaincardenas.com\/blog\/portraits-dhier-et-de-demain-1-juan-diego-vergara-ormeno-le-plasticien-peruvien\/guaman-poma-de-ayala-bd\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":370,"height":600,"file":"2020\/03\/Guaman-Poma-de-Ayala-BD.jpg","sizes":{"thumbnail":{"file":"Guaman-Poma-de-Ayala-BD-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/03\/Guaman-Poma-de-Ayala-BD.jpg?resize=150%2C150&ssl=1"},"medium":{"file":"Guaman-Poma-de-Ayala-BD-185x300.jpg","width":185,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/03\/Guaman-Poma-de-Ayala-BD.jpg?fit=185%2C300&ssl=1"},"post-thumbnail":{"file":"Guaman-Poma-de-Ayala-BD-370x288.jpg","width":370,"height":288,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/03\/Guaman-Poma-de-Ayala-BD.jpg?resize=370%2C288&ssl=1"},"large-feature":{"file":"Guaman-Poma-de-Ayala-BD-370x288.jpg","width":370,"height":288,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/03\/Guaman-Poma-de-Ayala-BD.jpg?resize=370%2C288&ssl=1"},"small-feature":{"file":"Guaman-Poma-de-Ayala-BD-185x300.jpg","width":185,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/03\/Guaman-Poma-de-Ayala-BD.jpg?fit=185%2C300&ssl=1"},"full":{"file":"Guaman-Poma-de-Ayala-BD.jpg?fit=370%2C600&ssl=1","width":370,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/03\/Guaman-Poma-de-Ayala-BD.jpg?fit=370%2C600&ssl=1"}},"image_meta":{"aperture":"2.2","credit":"","camera":"iPhone 6s","caption":"","created_timestamp":"1584541270","copyright":"","focal_length":"4.15","iso":"32","shutter_speed":"0.03030303030303","title":"","orientation":"1","keywords":[]}},"post":4837,"source_url":"https:\/\/alaincardenas.com\/blog\/wp-content\/uploads\/2020\/03\/Guaman-Poma-de-Ayala-BD.jpg","filename":"Guaman-Poma-de-Ayala-BD.jpg","filesize":103818,"_links":{"self":[{"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/media\/4848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/comments?post=4848"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":4837,"href":"https:\/\/alaincardenas.com\/blog\/wp-json\/wp\/v2\/posts\/4837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}